{"id":9204,"date":"2015-02-02T14:34:58","date_gmt":"2015-02-02T13:34:58","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=9204"},"modified":"2015-02-02T15:09:19","modified_gmt":"2015-02-02T14:09:19","slug":"lalevi-h-va-saber-patir-per-guanyar-per-la-minima","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/lalevi-h-va-saber-patir-per-guanyar-per-la-minima\/","title":{"rendered":"L&#8217;Alev\u00ed H va saber patir per guanyar per la m\u00ednima"},"content":{"rendered":"<p>Gran partit per part dels jugadors de la Fundaci\u00f3 Esportiva Grama. Al Municipal Nou Barris els colomencs van guanyar per un ajustat 3-4 davant el CF Monta\u00f1esa. La propera jornada s&#8217;enfrontaran a un rival directe, la Penya Barcelonista Barcino, a les 12:30 hores el dissabte com a visitants.<\/p>\n<p style=\"text-align: center;\">\n<p>Excel\u00b7lent primera meitat, on l&#8217;equip local es va avan\u00e7ar al marcador per\u00f2 els nostres no es van venir a baix i gr\u00e0cies als gols d&#8217;Aar\u00f3n, Joel, Ra\u00fal i Jean Paul van marxar amb un contundent 1-4 al descans. La Grama va desplegar un gran joc d&#8217;associaci\u00f3 i com era d&#8217;esperar l&#8217;equip local a la segona part no ho anava a posar gens f\u00e0cil.<\/p>\n<p style=\"text-align: center;\">\n<p>L&#8217;Alev\u00ed H de la FEG va saber patir i defensar-se davant un rival molt per sobre a la taula classificat\u00f2ria. Un xut de Ra\u00fal des de mig camp es va estavellar al travesser, aquest gol hagu\u00e9s tranquil\u00b7litzat el partit per als nostres interessos per\u00f2 finalment es va saber patir i es va aconseguir una vict\u00f2ria molt treballada i merescuda.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/10\/ALEV\u00cd-HFUNDACIO-GRAMA-SANTA-COLOMA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-8319\" alt=\"ALEV\u00cd H,FUNDACIO GRAMA SANTA COLOMA\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/10\/ALEV\u00cd-HFUNDACIO-GRAMA-SANTA-COLOMA.jpg\" width=\"512\" height=\"384\" \/><\/a><\/p>\n<p>Gran partido por parte de los jugadores de la Fundaci\u00f3 Esportiva Grama. En el Municipal Nou Barris los colomenses ganaron por un ajustado 3-4 ante el CF Monta\u00f1esa. La pr\u00f3xima jornada se enfrentar\u00e1n a un rival directo, la Penya Barcelonista Barcino, a las 12:30 horas el s\u00e1bado como visitantes.<\/p>\n<p>Excelente primera mitad, donde el equipo local se adelant\u00f3 en el marcador pero los nuestros no se vinieron a bajo y gracias a los tantos de Aar\u00f3n, Joel, Ra\u00fal y Jean Paul se marcharon con un contundente 1-4 al descanso. La Grama despleg\u00f3 un gran juego de asociaci\u00f3n y como era de esperar el equipo local en la segunda parte no lo iba a poner nada f\u00e1cil.<\/p>\n<p>El Alev\u00edn H de la FEG supo sufrir y defenderse ante un rival muy por encima en la tabla clasificatoria. Un disparo de Ra\u00fal desde medio campo se estrell\u00f3 en el larguero hubiera tranquilizado el partido para nuestros intereses\u00a0pero finalmente se supo sufrir y se consigui\u00f3 una victoria muy trabajada y merecida.<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=19628998&amp;CodGrupo=19976496&amp;CodTemporada=10&amp;CodJornada=1&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=19976496&amp;codcompeticion=19628998&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran partit per part dels jugadors de la Fundaci\u00f3 Esportiva Grama. Al Municipal Nou Barris els colomencs van guanyar per un ajustat 3-4 davant el CF Monta\u00f1esa. La propera jornada s&#8217;enfrontaran a un rival directe, la Penya Barcelonista Barcino, a les 12:30 hores el dissabte com a visitants. Excel\u00b7lent primera meitat, on l&#8217;equip local es [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[399,24,106,115],"class_list":["post-9204","post","type-post","status-publish","format-standard","hentry","category-alevins","tag-fegrama","tag-fundacio-esportiva-grama","tag-montanesa","tag-municipal-de-nou-barris"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/9204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=9204"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/9204\/revisions"}],"predecessor-version":[{"id":9205,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/9204\/revisions\/9205"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=9204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=9204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=9204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}