{"id":8928,"date":"2015-01-17T20:31:24","date_gmt":"2015-01-17T19:31:24","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=8928"},"modified":"2015-01-17T20:31:24","modified_gmt":"2015-01-17T19:31:24","slug":"lalevi-benjami-prebenjami-va-guanyar-a-badalona","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/lalevi-benjami-prebenjami-va-guanyar-a-badalona\/","title":{"rendered":"L&#8217;Alev\u00ed-Benjam\u00ed-Prebenjam\u00ed va guanyar a Badalona"},"content":{"rendered":"<p>L&#8217;Alev\u00ed-Benjam\u00ed-Prebenjam\u00ed Femen\u00ed FEG dirigit per Jordi P\u00e9rez va golejar a les setenes classificades de la lliga. Al Camp Municipal de Badalona les noies van guanyar 3-7 al CE Seagull. Els propers dos partits s\u00f3n davant els dos primers de la lliga, primer el dissabte 24 a les 13 hores a casa davant el segon, un CD Sant Gabriel \u00abB\u00bb invicte.<\/p>\n<p>El partit comen\u00e7ava amb un xut de Carla i una bona parada de la portera local. El conjunt colomenc estrenyia i poc a poc es feia amb el domini absolut del partit despr\u00e9s d&#8217;haver vist com en els primers minuts eren les badalonines les que dominaven. Sara tindria dues bones ocasions per\u00f2 tots dos xuts no van arribar per poc a ser gol.<\/p>\n<p>La Fundaci\u00f3 es mostrava molt perillosa i al final el gol acabaria arribant, Sara al minut 11 posava el 0-1. Les tres seg\u00fcents jugades abans del descans van ser un esc\u00e0ndol: Sara de cap al pal, Tatiana al travesser i al final una passada d&#8217;Ariadna a Carla acabaria amb el 0-2, Carla definia de meravelles picant la pilota a la portera.<\/p>\n<p>El segon quart del partit comen\u00e7ava amb un xut molt potent de Sara des migcamp que s&#8217;estavellaria al travesser. En un c\u00f3rner arribaria l&#8217;1-2 per\u00f2 seria un miratge ja que en la sacada de mig Sara chutar\u00eda des del mateix punt del centre del camp per marcar un gol\u00e0s.<\/p>\n<p>Abans del descans Yaiza afusellava la portera rival marcant per tot l&#8217;escaire. Despr\u00e9s del descans l&#8217;equip va mantenir el nivell per\u00f2 es va adormir i les locals es van posar 3-4 a quinze minuts del final. L&#8217;equip va aconseguir despertar i tornar a ser el dominador en atac i defensa del partit. I amb el despertar de la Fundaci\u00f3 arribarien tres gols m\u00e9s.<\/p>\n<p>De xut creuat Carla marcava un preci\u00f3s gol, Sara de falta directa el sis\u00e8 i Yaiza a un minut del final el definitiu 3-7.<\/p>\n<p><strong>Les millors fotos del partit en el seg\u00fcent link:\u00a0<\/strong><a href=\"https:\/\/plus.google.com\/photos\/113125192083830612262\/albums\/6105393706266605953\" target=\"_blank\">https:\/\/plus.google.com\/photos\/113125192083830612262\/albums\/6105393706266605953<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2015\/01\/P1010138.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-8930 aligncenter\" alt=\"OLYMPUS DIGITAL CAMERA\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2015\/01\/P1010138.jpg\" width=\"560\" height=\"419\" \/><\/a><\/p>\n<p>El Alev\u00edn-Benjam\u00edn-Prebenjam\u00edn Femenino FEG dirigido por Jordi P\u00e9rez gole\u00f3 a las s\u00e9ptimas clasificadas de la liga. En el Camp Municipal de Badalona las chicas ganaron 3-7 al CE Seagull.\u00a0Los pr\u00f3ximos dos partidos son ante los dos primeros de la liga, primero el s\u00e1bado 24 a las 13 horas en casa ante el segundo, un CD Sant Gabriel \u00abB\u00bb invicto.<\/p>\n<p>El partido empezaba con un disparo de Carla y una buena parada de la portera local. El conjunto colomense apretaba y poco a poco se hac\u00eda con el dominio absoluto del partido tras haber visto como en los primeros minutos eran las badalonesas las que dominaban. Sara tendr\u00eda dos buenas ocasiones pero ambos chutes no llegaron por poco a ser gol.<\/p>\n<p>La Fundaci\u00f3 se mostraba muy peligrosa y al final el gol acabar\u00eda llegando, Sara en el minuto 11 pon\u00eda el 0-1. Las tres siguientes jugadas antes del descanso fueron un esc\u00e1ndalo: Sara de cabeza al palo, Tatiana al larguero y al final un pase de Ariadna a Carla acabar\u00eda con el 0-2, Carla definia de maravillas picando la pelota a la portera.<\/p>\n<p>El segundo cuarto del partido empezaba con un disparo muy potente de Sara desde mediocampo que se estrellar\u00eda en el larguero. En un c\u00f3rner llegar\u00eda el 1-2 pero ser\u00eda un espejismo pues en el saque de mediocampo Sara chutar\u00eda desde el mismo punto del centro del campo para marcar un golazo.<\/p>\n<p>Antes del descanso Yaiza fusilaba a la portera rival marcando por toda la escuadra. Tras el descanso el equipo mantuvo el nivel pero se durmi\u00f3 y las locales se pusieron 3-4 a quince minutos del final. El equipo consigui\u00f3 despertar y volver a ser el dominador en ataque y defensa del partido. Y con el despertar de la Fundaci\u00f3 llegar\u00edan tres goles m\u00e1s.<\/p>\n<p>De tiro cruzado Carla marcaba un precioso gol, Sara de falta directa el sexto y Yaiza a un minuto del final el definitivo 3-7.<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=19629050&amp;CodGrupo=20236228&amp;CodTemporada=10&amp;CodJornada=1&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=20236228&amp;codcompeticion=19629050&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Alev\u00ed-Benjam\u00ed-Prebenjam\u00ed Femen\u00ed FEG dirigit per Jordi P\u00e9rez va golejar a les setenes classificades de la lliga. Al Camp Municipal de Badalona les noies van guanyar 3-7 al CE Seagull. Els propers dos partits s\u00f3n davant els dos primers de la lliga, primer el dissabte 24 a les 13 hores a casa davant el segon, un [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[210,399,24,208],"class_list":["post-8928","post","type-post","status-publish","format-standard","hentry","category-femeni","tag-camp-municipal-de-badalona","tag-fegrama","tag-fundacio-esportiva-grama","tag-seagull"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/8928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=8928"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/8928\/revisions"}],"predecessor-version":[{"id":8931,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/8928\/revisions\/8931"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=8928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=8928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=8928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}