{"id":822,"date":"2013-12-20T00:53:45","date_gmt":"2013-12-20T00:53:45","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=822"},"modified":"2013-12-20T00:53:45","modified_gmt":"2013-12-20T00:53:45","slug":"el-benjami-c-de-la-fundacio-jugara-contra-la-montanesa-al-municipal-de-nou-barris","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-benjami-c-de-la-fundacio-jugara-contra-la-montanesa-al-municipal-de-nou-barris\/","title":{"rendered":"El Benjam\u00ed C de la Fundaci\u00f3 jugar\u00e0 contra la Monta\u00f1esa al Municipal de Nou Barris"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-El <strong>Benjam\u00ed C de la Fundaci\u00f3<\/strong>, cinqu\u00e8 classificat, va aconseguir un important empat davant el tercer classificat, l&#8217;<strong>Unificaci\u00f3 Llefi\u00e0<\/strong>, per 3-3 i l&#8217;equip dirigit per <strong>Lautaro<\/strong> en la jornada seg\u00fcent, la 11, l&#8217;equip de la Fundaci\u00f3 es dirigir\u00e0 al <strong>Municipal de Nou Barris<\/strong> a enfrontar-se a la <strong>Monta\u00f1esa<\/strong>, des\u00e8 classificat, el proper dia 21 de desembre des de les 11 hores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-El Benjam\u00edn C de la Fundaci\u00f3, quinto clasificado, logr\u00f3 un importante empate ante el tercer clasificado, el Unificaci\u00f3n Llefi\u00e0, por 3-3 y el equipo dirigido por Lautaro en la jornada siguiente, la 11, el equipo de la Fundaci\u00f3 se dirigir\u00e1 al Municipal de Nou Barris a enfrentarse a la Monta\u00f1esa, d\u00e9cimo clasificado, el pr\u00f3ximo d\u00eda 21 de diciembre desde las 11 horas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-El Benjam\u00ed C de la Fundaci\u00f3, cinqu\u00e8 classificat, va aconseguir un important empat davant el tercer classificat, l&#8217;Unificaci\u00f3 Llefi\u00e0, per 3-3 i l&#8217;equip dirigit per Lautaro en la jornada seg\u00fcent, la 11, l&#8217;equip de la Fundaci\u00f3 es dirigir\u00e0 al Municipal de Nou Barris a enfrontar-se a la Monta\u00f1esa, des\u00e8 classificat, el proper dia 21 de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[114,106,115,110],"class_list":["post-822","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-benjamins","tag-benjami-c-de-la-fundacio","tag-montanesa","tag-municipal-de-nou-barris","tag-unificacio-llefia"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=822"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/822\/revisions"}],"predecessor-version":[{"id":824,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/822\/revisions\/824"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}