{"id":6774,"date":"2014-11-10T20:41:48","date_gmt":"2014-11-10T19:41:48","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=6774"},"modified":"2014-11-12T11:51:55","modified_gmt":"2014-11-12T10:51:55","slug":"el-juvenil-cadet-fe-grama-cau-davant-lue-cirera","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-juvenil-cadet-fe-grama-cau-davant-lue-cirera\/","title":{"rendered":"El Juvenil Cadet FE Grama cau davant l&#8217;UE Cirera"},"content":{"rendered":"<p>El Juvenil Cadet Femen\u00ed FE Grama dirigit per Amparo Bofarull va tornar a caure, aquesta vegada davant el sis\u00e8 classificat, equip que segueix invicte a la lliga.<\/p>\n<p>Les noies van rebre un dur 13-0 davant la UD Cirera. L&#8217;equip seguir\u00e0 una setmana m\u00e9s amb 0 punts a la pen\u00faltima posici\u00f3 de la taula.<\/p>\n<p>Diumenge a les 19:30 hores juguen a casa davant l&#8217;UE Vilassar de Mar, equip que porta nom\u00e9s nn punt, el seu rival directe.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/11\/fichatecudcirera130juvcatfem.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-6775\" alt=\"fichatecudcirera130juvcatfem\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/11\/fichatecudcirera130juvcatfem.jpg\" width=\"447\" height=\"381\" \/><\/a><\/p>\n<p>El Juvenil Cadete Femenino FE Grama dirigida por Amparo Bofarull volvi\u00f3 a caer, esta vez ante el sexto clasificado, equipo que sigue invicto en la liga.<\/p>\n<p>Las chicas recibieron un duro 13-0 ante la UD Cirera. El equipo seguir\u00e1 una semana m\u00e1s con 0 puntos en la pen\u00faltima posici\u00f3n de la tabla.<\/p>\n<p>El domingo a las 19:30 horas juegan en casa ante la UE Vilassar de Mar, equipo que solo lleva un punto, rival directo.<\/p>\n<p>&nbsp;<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=19629034&amp;CodGrupo=20234960&amp;CodTemporada=10&amp;CodJornada=1&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=20234960&amp;codcompeticion=19629034&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Juvenil Cadet Femen\u00ed FE Grama dirigit per Amparo Bofarull va tornar a caure, aquesta vegada davant el sis\u00e8 classificat, equip que segueix invicte a la lliga. Les noies van rebre un dur 13-0 davant la UD Cirera. L&#8217;equip seguir\u00e0 una setmana m\u00e9s amb 0 punts a la pen\u00faltima posici\u00f3 de la taula. Diumenge a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13],"tags":[358,24],"class_list":["post-6774","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-femeni","tag-cirera","tag-fundacio-esportiva-grama"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=6774"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6774\/revisions"}],"predecessor-version":[{"id":6777,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6774\/revisions\/6777"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=6774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=6774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=6774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}