{"id":6617,"date":"2014-11-08T10:50:39","date_gmt":"2014-11-08T09:50:39","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=6617"},"modified":"2014-11-08T10:50:48","modified_gmt":"2014-11-08T09:50:48","slug":"el-president-fegrama-antonio-morales-desitja-rapida-recuperacio-a-linfantil-chin-chan","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-president-fegrama-antonio-morales-desitja-rapida-recuperacio-a-linfantil-chin-chan\/","title":{"rendered":"El president FEGrama, Antonio Morales, desitja una r\u00e0pida recuperaci\u00f3 a l&#8217;infantil Chin Chan"},"content":{"rendered":"<p><span style=\"color: #000000;\">El passat dia 26 d\u2019Octubre, en el partit que enfrontava a l\u2019infantil D de la Fundaci\u00f3 Esportiva Grama contra el Santa Eulalia, en una jugada desafortunada, DANIEL GAMERO FERN\u00c1NDEZ va patir una fractura de Radi de la qual s\u2019est\u00e0 recuperant.<\/span><br \/>\n<span style=\"color: #000000;\">Els seus companys, mostrant els valors que aquesta Fundaci\u00f3 vol transmetre als m\u00e9s joves, van lluir samarretes d\u2019\u00e0nim al partit que van disputar aquest cap de setmana i, a m\u00e9s, han signat una pilota per tal de desitjar-li una r\u00e0pida recuperaci\u00f3 a \u201cChin-Chan\u201d com amigablement el coneixen.<\/span><br \/>\n<span style=\"color: #000000;\">Aquesta tarda, el nostre President, Antonio Morales, ha fet entrega d\u2019aquesta pilota signada i tamb\u00e9 s\u2019ha interessat per la seva recuperaci\u00f3. Recordem que Daniel Gamero \u00e9s un dels infantils amb m\u00e9s projecci\u00f3 i que ja ha debutat amb l\u2019Infantil A de categoria Preferent.<\/span><br \/>\n<span style=\"color: #000000;\">Com ja ha pogut sentir de veu del President, tots esperem que es recuperi tan aviat com sigui possible.<\/span><\/p>\n<figure id=\"attachment_6618\" aria-describedby=\"caption-attachment-6618\" style=\"width: 540px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/11\/chinchanmorales.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6618\" alt=\"chinchan con antonio morales a la fundaci\u00f3 grama de santa coloma\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/11\/chinchanmorales.jpg\" width=\"540\" height=\"960\" \/><\/a><figcaption id=\"caption-attachment-6618\" class=\"wp-caption-text\">chinchan con antonio morales a la fundaci\u00f3 grama de santa coloma<\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">El pasado d\u00eda 26 de Octubre, en el partido que enfrentaba al Infantil D de la Fundaci\u00f3 Esportiva Grama contra el Santa Eulalia, en una jugada desafortunada, DANIEL GAMERO FERN\u00c1NDES sufri\u00f3 una fractura del Radio de la cual se est\u00e1 recuperando.<\/span><br \/>\n<span style=\"color: #000000;\">Sus compa\u00f1eros, mostrando los valores que esta Fundaci\u00f3 quiere transmitir a los m\u00e1s j\u00f3venes, lucieron camisetas de \u00e1nimo en el partido que disputaron este fin de semana y, adem\u00e1s, han firmado un bal\u00f3n para desearle una pronta recuperaci\u00f3n a \u201cChin-Chan\u201d como amigablemente le conocen.<\/span><br \/>\n<span style=\"color: #000000;\">Esta tarde, nuestro Presidente, Antonio Morales, ha hecho entrega de esta pelota firmada y tambi\u00e9n se ha interesado por su recuperaci\u00f3n. Recordamos que Daniel Gamero es uno de los infantiles con m\u00e1s proyecci\u00f3n y que ya ha debutado con el Infantil A de categor\u00eda Preferente.<\/span><br \/>\n<span style=\"color: #000000;\">Como ya ha podido sentir de voz del Presidente, todos esperamos que se recupere tan pronto como sea posible.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El passat dia 26 d\u2019Octubre, en el partit que enfrontava a l\u2019infantil D de la Fundaci\u00f3 Esportiva Grama contra el Santa Eulalia, en una jugada desafortunada, DANIEL GAMERO FERN\u00c1NDEZ va patir una fractura de Radi de la qual s\u2019est\u00e0 recuperant. Els seus companys, mostrant els valors que aquesta Fundaci\u00f3 vol transmetre als m\u00e9s joves, van [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[20,21],"class_list":["post-6617","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-fundacio-grama","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=6617"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6617\/revisions"}],"predecessor-version":[{"id":6620,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6617\/revisions\/6620"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=6617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=6617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=6617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}