{"id":6392,"date":"2014-11-04T10:55:45","date_gmt":"2014-11-04T08:55:45","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=6392"},"modified":"2014-11-04T14:31:51","modified_gmt":"2014-11-04T12:31:51","slug":"lalevi-d-fegrama-puja-a-la-tercera-placa-amb-la-golejada-als-salesians-bosco-horta-per-1-5","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/lalevi-d-fegrama-puja-a-la-tercera-placa-amb-la-golejada-als-salesians-bosco-horta-per-1-5\/","title":{"rendered":"L\u2019Alev\u00ed D FEGrama puja a la tercera pla\u00e7a amb la golejada als Salesians Bosco-Horta per 1-5"},"content":{"rendered":"<p><span style=\"color: #000000;\">L&#8217;Alev\u00ed D FEGrama dirigit per Aitor Mezquiriz i Albert Massa ha tornat a emportar-se la vict\u00f2ria amb golejada en la seva visita als Salesians Bosco-Horta per 1-5.<\/span><\/p>\n<p>\u00c9s la quarta vict\u00f2ria consecutiva que el situen tercer classificat en el grup de quatre equips amb 12 punts a remolc del Badalona, amb 15.<\/p>\n<p>El conjunt de la Fundaci\u00f3 Grama ha remuntat dela quarta posici\u00f3 gr\u00e0cies al triplet de gols d&#8217;Adri\u00e1n Guti\u00e9rrez Camps, al gol de Joao Fernando i al penal transformat per David Romeu.<\/p>\n<p>Per a la jornada 6, el conjunt de la Fundaci\u00f3 Grama rebr\u00e0 a Santa Coloma a l&#8217;Escola Premier Barcelona, cinqu\u00e8 classificat, el diumenge 2 de novembre des de les 14.10 hores.<\/p>\n<p>El Alev\u00edn D FEGrama dirigido por Aitor Mezquiriz y Albert Massa ha vuelto a llevarse la victoria con goleada en su visita a los salesians Bosco-Horta por 1-5.<\/p>\n<p>Es la cuarta victoria consecutiva que le sit\u00faan tercer clasificado en el grupo de cuatro equipos con 12 puntos a remolque del Badalona, con 15.<\/p>\n<p>El conjunto de la Fundaci\u00f3 Grama ha remontado dela cuarta posici\u00f3n gracias al triplete de goles de Adri\u00e1n Guti\u00e9rrez Campos, al gol de Joao Fernando y al penalti transformado por David Romeu.<\/p>\n<p>Para la jornada 6, el conjunto de la Fundaci\u00f3 Grama recibir\u00e1 en Santa Coloma a la Escola Premier Barcelona, quinto clasificado, el domingo 2 de noviembre desde las 14:10 horas.<\/p>\n<div>\n<dl id=\"attachment_6071\">\n<dt><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/10\/Alevi__D_FEG-BONPASTOR@chemacarva030.jpg\"><img loading=\"lazy\" decoding=\"async\" alt=\"Alevi__D_FEG fundacio grama Santa Coloma BON PASTOR @chemacarva\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/10\/Alevi__D_FEG-BONPASTOR@chemacarva030.jpg\" width=\"640\" height=\"480\" \/><\/a><\/dt>\n<dd>Alevi__D_FEG fundacio grama Santa Coloma BON PASTOR @chemacarva<\/dd>\n<\/dl>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Al\u00e9 Grama!!!<\/p>\n<p>Llegeix m\u00e9s articles\/Lee\u00a0 m\u00e1s art\u00edculos:<\/p>\n<p>Participa al Gran Concurs de Nadal de la Fundaci\u00f3 Esportiva Grama\u00a0<a href=\"https:\/\/fegrama.cat\/web\/?p=6364\" target=\"_blank\">https:\/\/fegrama.cat\/web\/?p=6364<\/a><\/p>\n<p>El Juvenil A FEGrama treu un clar triomf al Nou Sardenya de l&#8217;Europa per 0-2<br \/>\n<a href=\"https:\/\/fegrama.cat\/web\/?p=6206\" target=\"_blank\">https:\/\/fegrama.cat\/web\/?p=6206<\/a><br \/>\nEl Juvenil Cadet Femen\u00ed FEGrama perd contra el Santa Susanna\u00a0<a href=\"https:\/\/fegrama.cat\/web\/?p=6316\" target=\"_blank\">https:\/\/fegrama.cat\/web\/?p=6316<\/a><br \/>\nEl Cadet B FEGrama remunta i guanya al Municipal Andrade Sant Mart\u00ed del Sant Mart\u00ed-Condal per 2-4\u00a0<a href=\"https:\/\/fegrama.cat\/web\/?p=6216\" target=\"_blank\">https:\/\/fegrama.cat\/web\/?p=6216<\/a><\/p>\n<p>[divider]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=19628998&amp;CodGrupo=19976597&amp;CodTemporada=10&amp;CodJornada=1&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=19976597&amp;codcompeticion=19628998&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Alev\u00ed D FEGrama dirigit per Aitor Mezquiriz i Albert Massa ha tornat a emportar-se la vict\u00f2ria amb golejada en la seva visita als Salesians Bosco-Horta per 1-5. \u00c9s la quarta vict\u00f2ria consecutiva que el situen tercer classificat en el grup de quatre equips amb 12 punts a remolc del Badalona, amb 15. El conjunt de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[24,798,21],"class_list":["post-6392","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-fundacio-esportiva-grama","tag-salesians-bosco-horta","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=6392"}],"version-history":[{"count":4,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6392\/revisions"}],"predecessor-version":[{"id":6422,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/6392\/revisions\/6422"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=6392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=6392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=6392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}