{"id":4903,"date":"2014-09-03T11:47:19","date_gmt":"2014-09-03T09:47:19","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=4903"},"modified":"2014-09-04T21:20:04","modified_gmt":"2014-09-04T19:20:04","slug":"si-has-nascut-al-2009-2010-i-2011-vine-a-jugar-a-lescola-de-la-fundacio-grama","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/si-has-nascut-al-2009-2010-i-2011-vine-a-jugar-a-lescola-de-la-fundacio-grama\/","title":{"rendered":"Si has nascut al 2009, 2010 i 2011 vine a jugar a l&#8217;Escola de la Fundaci\u00f3 Grama"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la <strong>Fundaci\u00f3 Grama<\/strong> estem molt orgullosos de poder anunciar als nous formadors dels m\u00e9s petits a la nostra Escola on destaquen dos jugadors del Juvenil, el <strong>Brian Caicedo i el Maikol M\u00e1rquez<\/strong>, a m\u00e9s de les noves incorporacions de <strong>Cristian Alonso, Albert Jim\u00e9nez i Carlos Guerrero<\/strong> que donaran suport al coordinador <strong>Juan Cervantes<\/strong> i l&#8217;altre veter\u00e0 entrenador, <strong>Mart\u00edn<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A tots ells, el nostre coordinador de \u00a0l&#8217;Escola,\u00a0<strong>Joan Arag\u00f3<\/strong>, els ha facilitat un <strong>Dossier de Metodologia Global<\/strong> que, alhora, \u00e9s informatiu i pr\u00e0ctic on es resumeixen les actituds tant esportives com personals que insuflarem als m\u00e9s petits i que s\u00f3n base fonamental en la formaci\u00f3 de persones i jugadors a la Fundaci\u00f3 Grama, des de saber respectar el contrari (tamb\u00e9 entra la <strong>Toler\u00e0ncia 0<\/strong> a la grada on no passarem cap insult ni ofenses) fins a recollir i ordenar el material esportiu.<\/span><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aix\u00ed que si coneixes a algun nen\/a nascut entre <strong>2009, 2010 i 2011<\/strong>, i que vulgui desenvolupar-se com jugador dins d&#8217;un grup hum\u00e0 ple de professionals de l&#8217;esport, acosta&#8217;t al Nou Municipal de Santa Coloma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Felicitacions a tots ells!<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/09\/aa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4905\" alt=\"aa\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/09\/aa.jpg\" width=\"736\" height=\"441\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la Fundaci\u00f3 Grama estamos muy orgullosos de poder anunciar a los nuevos formadores de los m\u00e1s peque\u00f1os en nuestra Escuela donde destacan dos jugadores del Juvenil, el Brian Caicedo y el Maikol M\u00e1rquez, adem\u00e1s de las nuevas incorporaciones de Cristian Alonso, Albert Jim\u00e9nez y Carlos Guerrero que apoyar\u00e1n el coordinador Juan Cervantes y el otro veterano entrenador, Mart\u00edn.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A todos ellos, nuestro coordinador de F\u00fatbol 7, Juan Arag\u00f3n, les ha facilitado un Dossier de Metodolog\u00eda Global que, al mismo tiempo, es informativo y pr\u00e1ctico donde se resumen las actitudes tanto deportivas como personales que insufla a los m\u00e1s peque\u00f1os y que son base fundamental en la formaci\u00f3n de personas y jugadores en la Fundaci\u00f3n Grama, desde saber respetar lo contrario (tambi\u00e9n entra la Tolerancia 0 en la grada donde no pasaremos ning\u00fan insulto ni ofensas) hasta recoger y ordenar el material deportivo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">As\u00ed que si conoces a alg\u00fan ni\u00f1o \/ a nacido entre 2009, 2010 y 2011, y que quiera desarrollarse como jugador dentro de un grupo humano lleno de profesionales del deporte, ac\u00e9rcate el Nou Municipal de Santa Coloma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00a1Felicitaciones a todos ellos!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Text i fotos: @ChemaCarva<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cartel: Dani Borrallo<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A la Fundaci\u00f3 Grama estem molt orgullosos de poder anunciar als nous formadors dels m\u00e9s petits a la nostra Escola on destaquen dos jugadors del Juvenil, el Brian Caicedo i el Maikol M\u00e1rquez, a m\u00e9s de les noves incorporacions de Cristian Alonso, Albert Jim\u00e9nez i Carlos Guerrero que donaran suport al coordinador Juan Cervantes i [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[20,643,27,21,721],"class_list":["post-4903","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-fundacio-grama","tag-futbol","tag-nou-municipal","tag-santa-coloma","tag-tolerancia-0"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/4903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=4903"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/4903\/revisions"}],"predecessor-version":[{"id":4909,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/4903\/revisions\/4909"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=4903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=4903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=4903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}