{"id":3015,"date":"2014-03-28T08:35:54","date_gmt":"2014-03-28T07:35:54","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=3015"},"modified":"2014-03-26T19:37:36","modified_gmt":"2014-03-26T18:37:36","slug":"laleviinfantil-femeni-de-la-fegrama-anira-dissabte-a-casa-del-martinenc","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/laleviinfantil-femeni-de-la-fegrama-anira-dissabte-a-casa-del-martinenc\/","title":{"rendered":"L&#8217;Alev\u00ed\/Infantil Femen\u00ed de la FEGrama anir\u00e0 dissabte a casa del Martinenc"},"content":{"rendered":"<p>L&#8217;Alev\u00ed\/Infantil Femen\u00ed de la FEGrama dirigit per Goretti voldr\u00e0 canviar de tend\u00e8ncia despr\u00e8s de caure a casa amb la visita del l\u00edder, la Penya Blanc i Blava La Roca, per 0-2.<\/p>\n<p>El conjunt de la Fundaci\u00f3 Grama per\u00f2 continu\u00e0 a la sisena posici\u00f3 amb els grups de dalt de la taula amb la suma d&#8217;aquests 37 punts perqu\u00e8 els dos perseguidors immediats han caigut tamb\u00e9: el Santa Perp\u00e8tua a casa del Seagull per 7-0 i el Martinenc a la seva visita al cinqu\u00e8 classificat, el Vilanova, per un ajustat 5-4.<\/p>\n<p>A la jornada 22 el conjunt femen\u00ed de la Fundaci\u00f3 Grama viatjar\u00e0 al Municipal del Guinard\u00f3 contra el Martinenc, vuit\u00e8 amb 34 punts, el dissabte dia 29 de mar\u00e7 a les 13:30 hores.<\/p>\n<p>[divider]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=18473338&amp;CodGrupo=18699563&amp;CodTemporada=9&amp;CodJornada=10&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=18699563&amp;codcompeticion=18473338&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n<p>El Alev\u00edn \/ Infantil Femenino de la FEGRAM dirigido por Goretti querr\u00e1 cambiar de tendencia despu\u00e9s de caer en casa con la visita del l\u00edder, la Pe\u00f1a Blanco y Azul La Roca, por 0-2.<br \/>\nEl conjunto de la Fundaci\u00f3n Grama pero continu\u00f3 en la sexta posici\u00f3n con los grupos de arriba de la tabla con la suma de estos 37 puntos para que los dos perseguidores inmediatos han ca\u00eddo tambi\u00e9n el Santa Perp\u00e8tua en casa del Seagull por 7-0 y el Martinenc a su visita al quinto clasificado, el Vilanova, por un ajustado 5-4.<\/p>\n<p>En la jornada 22 el conjunto femenino de la Fundaci\u00f3n Grama viajar\u00e1 el Municipal del Guinard\u00f3 contra el Martinenc, octavo con 34 puntos, el s\u00e1bado d\u00eda 29 de marzo a las 13:30 horas.<\/p>\n<p><strong>Visca l&#8217;Esperit Grama!!!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Alev\u00ed\/Infantil Femen\u00ed de la FEGrama dirigit per Goretti voldr\u00e0 canviar de tend\u00e8ncia despr\u00e8s de caure a casa amb la visita del l\u00edder, la Penya Blanc i Blava La Roca, per 0-2. El conjunt de la Fundaci\u00f3 Grama per\u00f2 continu\u00e0 a la sisena posici\u00f3 amb els grups de dalt de la taula amb la suma d&#8217;aquests [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-3015","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-femeni"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/3015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=3015"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/3015\/revisions"}],"predecessor-version":[{"id":3017,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/3015\/revisions\/3017"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=3015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=3015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=3015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}