{"id":29055,"date":"2021-06-24T16:35:46","date_gmt":"2021-06-24T15:35:46","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=29055"},"modified":"2021-06-24T16:35:47","modified_gmt":"2021-06-24T15:35:47","slug":"previes-jornada-26-27-de-juny","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/previes-jornada-26-27-de-juny\/","title":{"rendered":"Pr\u00e8vies Jornada 26\/27 de Juny"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aquesta setmana volem destacar els seg\u00fcents partits del nostre futbol base:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juvenil B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquest dissabte a les 12:30h podem ser campions de la 1\u00aa divisi\u00f3 al Nou Municipal de Santa Coloma. Rebem a la Fundaci\u00f3 P. CE. J\u00fapiter \u00abA\u00bb, que ara mateix es troba a la tercera posici\u00f3.  Hem de guanyar el nostre partit i esperar que el l\u00edder no ho faci en el seu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjam\u00ed A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Municipal de Llefi\u00e0 pot ser testimoni de com el nostre Benjam\u00ed A es proclama campi\u00f3 de la 1\u00aa divisi\u00f3 si es capa\u00e7 de guanyar al CF Unificaci\u00f3n Llefi\u00e0 \u00abA\u00bb aquest dissabte a les 9:00h. Haurem d&#8217;estar molt atents al partit i li desitgem la millor de les sorts als colomencs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00ed B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Nou Municipal de Santa Coloma acollir\u00e0 aquest dissabte a les 8:45h el partit de l&#8217;alev\u00ed B de la FE Grama davant el FC Martinenc \u00abA\u00bb. Partit corresponent a la 1\u00aa divisi\u00f3 a on necessitarem el suport de l&#8217;afici\u00f3 per sumar el 3 punts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00ed D<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dissabte a les 13:15h visitem el CEM Can Caralleu per enfrontar-nos al CP Sarri\u00e0 \u00abC\u00bb, en el partit corresponent a l&#8217;\u00faltima jornada de la 2\u00aa divisi\u00f3. Hem d&#8217;acabar de la millor manera possible i guanyar fora de casa a un rival com el Sarri\u00e0 seria excel\u00b7lent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cadet C<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Camp de Futbol Escola Industrial acollir\u00e0 l&#8217;\u00faltima jornada de lliga de la 1\u00aa divisi\u00f3 entre els colomencs i la P\u00aa Barc. Anguera \u00abB\u00bb aquest diumenge 27 de juny a les 16:00h. Ser\u00e0 un partit molt igualat i disputat a on ho haurem de fer molt b\u00e9 si volem sumar els \u00faltims 3 punts.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"371\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/04\/image-22.png\" alt=\"\" class=\"wp-image-28596\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/04\/image-22.png 563w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/04\/image-22-300x198.png 300w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prebenjam\u00ed B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ens toca visitar el Poliesportiu de la Mina aquest dissabte 26 de juny per jugar a les 9:00h davant el CD Sant Gabriel, en el partit corresponent a l&#8217;ultima jornada de la lliga CADECA. Estem molt orgullosos dels nostres nois per la temporada que han fet i per jugar d&#8217;aquesta manera tan espectacular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infantil A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquest dissabte a les 17:00h es jugar\u00e0 el partit corresponent a la divisi\u00f3 Preferent entre l&#8217;Infantil A de la Grama i el CE Europa \u00abA\u00bb al Municipal Nou Sardenya. Dos equips amb molt bones defenses que voldran guanyar l&#8217;\u00faltim partit de la temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infantil B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ZEM Bufal\u00e0 ens acollir\u00e0 aquest diumenge a les 11:15h per disputar l&#8217;\u00faltim partit de la temporada davant el CF Bufal\u00e0 \u00abA\u00bb de la 1\u00aa divisi\u00f3. Rival amb una regularitat espectacular i que s&#8217;ha mantingut tota la temporada en la part alta de la classificaci\u00f3. Gran repte per davant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cadet A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diumenge a les 12:00h el Nou Municipal de Santa Coloma veur\u00e0 com els nostres nois juguen davant el CF Damm \u00abB\u00bb el partit corresponent a la divisi\u00f3 Preferent. Hem sumat la majoria dels punts a casa i volem acabar de la millor manera possible davant un gran rival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00ed E<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al CEM Bes\u00f2s &#8211; Traiana la FE Grama jugar\u00e0 davant el CE Sant Adri\u00e0 2020 \u00abA\u00bb en el partit corresponent a la 3\u00aa divisi\u00f3. El partit es disputar\u00e0 aquest dissabte a les 10:00h i volem continuar amb la bona din\u00e0mica ascendent que portem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordeu que podreu veure a les xarxes socials del club la agenda de partits d\u2019aquest cap de setmana del nostre futbol base.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Previas Jornada 26\/27 de Junio<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana queremos destacar los siguientes partidos de nuestro f\u00fatbol base:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Juvenil B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este s\u00e1bado a las 12:30h\u00a0podemos ser campeones de la\u00a01\u00aa\u00a0divisi\u00f3n en el Nou Municipal de Santa Coloma. Recibimos a la Fundaci\u00f3 P. CE. J\u00fapiter \u00abA\u00bb, que ahora mismo se encuentra en la tercera posici\u00f3n. Tenemos que ganar nuestro partido y esperar que el l\u00edder no lo haga en el suyo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjam\u00edn A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Municipal de\u00a0Llefi\u00e0\u00a0puede ser testigo de como nuestro Benjam\u00edn A se proclama campe\u00f3n de la\u00a01\u00aa\u00a0divisi\u00f3n si es capaz de ganar al\u00a0CF\u00a0Unificaci\u00f3n\u00a0Llefi\u00e0\u00a0\u00abA\u00bb este s\u00e1bado a las 9:00h. Tendremos que estar muy atentos al partido y le deseamos la mejor de las suertes a los\u00a0colomenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00edn B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Nou Municipal de Santa Coloma acoger\u00e1 este s\u00e1bado a las 8:45h\u00a0el partido del alev\u00edn B de la FE\u00a0Grama\u00a0ante el FC\u00a0Martinenc\u00a0\u00abA\u00bb. Partido correspondiente a la\u00a01\u00aa\u00a0divisi\u00f3n donde necesitaremos el apoyo de la afici\u00f3n para sumar los 3 puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00edn D<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e1bado a las 13:15h\u00a0visitamos el\u00a0CEM\u00a0Can\u00a0Caralleu\u00a0para enfrentarnos al CP Sarri\u00e0 \u00abC\u00bb, en el partido correspondiente a la \u00faltima jornada de la\u00a02\u00aa\u00a0divisi\u00f3n. Tenemos que acabar de la mejor manera posible y ganar fuera de casa a un rival como el Sarri\u00e0 ser\u00eda excelente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cadete C<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Camp de Futbol Escola Industrial acoger\u00e1 la \u00faltima jornada de liga de la\u00a01\u00aa\u00a0divisi\u00f3n entre los\u00a0colomenses\u00a0y la\u00a0P\u00aa\u00a0Barc.\u00a0Anguera\u00a0\u00abB\u00bb este domingo 27 de junio a las 16:00h. Ser\u00e1 un partido muy igualado y disputado donde lo tendremos que hacer muy bien si queremos sumar los \u00faltimos 3 puntos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"719\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/05\/JuvB2021-1-1024x719.jpeg\" alt=\"\" class=\"wp-image-28891\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/05\/JuvB2021-1-1024x719.jpeg 1024w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/05\/JuvB2021-1-300x211.jpeg 300w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/05\/JuvB2021-1-768x540.jpeg 768w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2021\/05\/JuvB2021-1.jpeg 1143w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prebenjam\u00edn B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos toca visitar el Poliesportiu de la Mina este s\u00e1bado 26 de junio para jugar a las 9:00h\u00a0ante el CD Sant Gabriel, en el partido correspondiente a la \u00faltima jornada de la liga\u00a0CADECA. Estamos muy orgullosos de nuestros chicos por la temporada que han hecho y para jugar de este modo tan espectacular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infantil A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este s\u00e1bado a las 17:00h\u00a0se jugar\u00e1 el partido correspondiente a la divisi\u00f3n Preferente entre el Infantil A de la\u00a0Grama\u00a0y el CE Europa \u00abA\u00bb en el Municipal Nou Sardenya. Dos equipos con muy buenas defensas que querr\u00e1n ganar el \u00faltimo partido de la temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Infantil B<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\u00a0ZEM\u00a0Bufal\u00e0\u00a0nos acoger\u00e1 este domingo a las 11:15h\u00a0para disputar el \u00faltimo partido de la temporada ante el\u00a0CF\u00a0Bufal\u00e0\u00a0\u00abA\u00bb de la\u00a01\u00aa\u00a0divisi\u00f3n. Rival con una regularidad espectacular y que se ha mantenido toda la temporada en la parte alta de la clasificaci\u00f3n. Gran reto por delante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cadete A<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Domingo a las 12:00h\u00a0el Nou Municipal de Santa Coloma ver\u00e1 como nuestros chicos juegan ante el\u00a0CF\u00a0Damm\u00a0\u00abB\u00bb el partido correspondiente a la divisi\u00f3n Preferente. Hemos sumado la mayor\u00eda de los puntos en casa y queremos acabar de la mejor manera posible ante un gran rival.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alev\u00edn E<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el\u00a0CEM\u00a0Bes\u00f2s\u00a0&#8211;\u00a0Traiana\u00a0la FE\u00a0Grama\u00a0jugar\u00e1 ante el CE Sant Adri\u00e0 2020 \u00abA\u00bb en el partido correspondiente a la\u00a03\u00aa\u00a0divisi\u00f3n. El partido se disputar\u00e1 este s\u00e1bado a las 10:00h\u00a0y queremos continuar con la buena din\u00e1mica ascendente que llevamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordad que podr\u00e9is ver en las redes sociales del club la agenda de partidos de este fin de semana de nuestro f\u00fatbol base.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquesta setmana volem destacar els seg\u00fcents partits del nostre futbol base: Juvenil B Aquest dissabte a les 12:30h podem ser campions de la 1\u00aa divisi\u00f3 al Nou Municipal de Santa Coloma. Rebem a la Fundaci\u00f3 P. CE. J\u00fapiter \u00abA\u00bb, que ara mateix es troba a la tercera posici\u00f3. Hem de guanyar el nostre partit i [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":28570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10,11,7,9,6,12],"tags":[],"class_list":["post-29055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-de-partits","category-alevins","category-benjamins","category-cadets","category-infantils","category-juvenils","category-prebenjamins"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/29055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=29055"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/29055\/revisions"}],"predecessor-version":[{"id":29056,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/29055\/revisions\/29056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/28570"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=29055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=29055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=29055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}