{"id":2653,"date":"2014-03-14T07:45:14","date_gmt":"2014-03-14T06:45:14","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2653"},"modified":"2014-03-13T19:48:28","modified_gmt":"2014-03-13T18:48:28","slug":"el-cadet-a-de-la-fegrama-anira-dissbte-a-medir-se-al-llefia","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-cadet-a-de-la-fegrama-anira-dissbte-a-medir-se-al-llefia\/","title":{"rendered":"El Cadet A de la FEGrama anir\u00e0 dissbte a medir-se al Llefi\u00e0"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la jornada passada, el\u00a0<strong>Cadet A de la FEGrama<\/strong>\u00a0no va poder rematar la bona feina davant el\u00a0<strong>Manlleu <\/strong>\u00a0i finalment l&#8217;empat a dos gols va ser el resultat a la conclusi\u00f3 del partit d&#8217;un rival directe on la dist\u00e0ncia continua d&#8217;un sol punt.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El conjunt de <strong>Ram\u00f3n Mart\u00ednez i Manu Garc\u00eda<\/strong> suma amb aquest el segon empat dels \u00faltims cinc partits i puja a l&#8217;onzena pla\u00e7a a aquest grup 2 d&#8217;on voldr\u00e0 seguir sumant i pujar al lloc on es mereix.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per aix\u00f2 a la pr\u00f2xima jornada 20, dissabte dia 15 de mar\u00e7 des de les 18:00 hores el conjunt de la\u00a0<strong>Fundaci\u00f3 Grama<\/strong>\u00a0viatjar\u00e0 al camp ve\u00ed del Municipal de\u00a0<strong>Llefi\u00e0<\/strong>, vuit\u00e8 amb 31 punts.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">[divider]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=18473293&amp;CodGrupo=18491106&amp;CodTemporada=9&amp;CodJornada=10&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=18491106&amp;codcompeticion=18473293&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la pasada jornada, el Cadete A de la FEGRAM no pudo rematar el buen trabajo ante el Manlleu y finalmente el empate a dos goles fue el resultado a la conclusi\u00f3n del partido de un rival directo donde la distancia sigue de un solo punto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El conjunto de Ram\u00f3n Mart\u00ednez y Manu Garc\u00eda suma con este el segundo empate de los \u00faltimos cinco partidos y asciende a la und\u00e9cima plaza en este grupo 2 donde querr\u00e1 seguir sumando y subir al lugar donde se merece.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por eso en la pr\u00f3xima jornada 20, el s\u00e1bado d\u00eda 15 de marzo desde las 18:00 horas el conjunto de la Fundaci\u00f3n Grama viajar\u00e1 al campo vecino del Municipal de Llefi\u00e0, octavo con 31 puntos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la jornada passada, el\u00a0Cadet A de la FEGrama\u00a0no va poder rematar la bona feina davant el\u00a0Manlleu \u00a0i finalment l&#8217;empat a dos gols va ser el resultat a la conclusi\u00f3 del partit d&#8217;un rival directe on la dist\u00e0ncia continua d&#8217;un sol punt. El conjunt de Ram\u00f3n Mart\u00ednez i Manu Garc\u00eda suma amb aquest el segon [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[19,20,152,27,21],"class_list":["post-2653","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-cadets","tag-feg","tag-fundacio-grama","tag-municipal-de-llefia","tag-nou-municipal","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2653"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2653\/revisions"}],"predecessor-version":[{"id":2655,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2653\/revisions\/2655"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}