{"id":26491,"date":"2019-03-18T00:15:20","date_gmt":"2019-03-17T23:15:20","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=26491"},"modified":"2019-03-18T00:15:20","modified_gmt":"2019-03-17T23:15:20","slug":"dos-empats-i-una-victoria-la-del-juvenil-c","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/dos-empats-i-una-victoria-la-del-juvenil-c\/","title":{"rendered":"Dos empats i una vict\u00f2ria, la del Juvenil C."},"content":{"rendered":"<p><strong>Juvenil A:<\/strong><\/p>\n<p>Unificacion Llefia 2 JA 2<\/p>\n<p>El Juvenil A treu un punt d&#8217;un camp complicat com \u00e9s el del Llefi\u00e0, punt que despr\u00e9s de la derrota de l&#8217;Sants pot fer-ho bo la propera jornada a Cornell\u00e0.<br \/>\nEl partit va comen\u00e7ar amb la Fundaci\u00f3 molt ficada i un Llefi\u00e0 molt agressiu en el joc a la vora del reglament, ja es preveia un partit intens, tot i aix\u00ed, els de Santa Coloma mai van perdre la cara al partit.<br \/>\nEn el minut 16 i despr\u00e9s d&#8217;una gran jugada combinativa \u00c0ngel, cedia una pilota a Montalb\u00e1n que posava el 0-1, gol que seria anul\u00b7lat per un fora de joc inexistent, set minuts despr\u00e9s, en el 23 i despr\u00e9s d&#8217;una falta bugada des del seu propi camp, el davanter dels locals guanyava el salt al defensa colomenc i de cap cap al 1-0. La reacci\u00f3 dels blaus va ser bona i aviat van comen\u00e7ar a generar ocasions buscant l&#8217;empat, empat que arribaria en el minut 37 amb un cop de cap de Lucas a la sortida d&#8217;un c\u00f3rner. Amb aquest resultat s&#8217;arribaria al descans.<br \/>\nA la represa 01:00 Grama molt millor plantada buscava incisivament la vict\u00f2ria, \u00c0ngel, Montalban i Bruno, amb un xut al travesser, van disposar de tres clares ocasions per posar els visitants per davant en el marcador. Per\u00f2 havia de ser el conjunt de Badalona qui despr\u00e9s d&#8217;una falta a la frontal i amb un colpeig magistral, feia el 2-1. Moments de desconcert del nostre Juvenil, que va aprofitar el Llefia per tenir una ocasi\u00f3 de fer el tercer gol, per\u00f2 aquesta va estar b\u00e9 tallada per Nofu. Al minut 72 i despr\u00e9s d&#8217;una jugada afortunada Montalban posava les taules en el marcador, 2-2. \u00c9s aqu\u00ed quan els colomencs van buscar la vict\u00f2ria que al final no van poder aconseguir.<br \/>\nManu Pel\u00e1ez; estic orgull\u00f3s dels meus jugadors, tenen moltes ganes d&#8217;aconseguir els objectius, entrenen al 200% i ho han intentat fins al final. Ja nom\u00e9s pensem en tornar de dimarts a la feina per preparar el partit davant Cornell\u00e0.<\/p>\n<p>Unificacion Llefia 2 JA 2<\/p>\n<p>El Juvenil A saca un punto de un campo complicado como es el del Llefi\u00e1, punto que tras la derrota del Sants puede hacerlo bueno la pr\u00f3xima jornada en Cornell\u00e1.<br \/>\nEl partido empez\u00f3 con la Fundaci\u00f3n muy metida y un Llefi\u00e1 muy agresivo en el juego al borde del reglamento, ya se preve\u00eda un partido intenso, a\u00fan as\u00ed, los de Santa Coloma nunca perdieron la cara al partido.<br \/>\nEn el minuto 16 y tras una gran jugada combinativa \u00c1ngel, ced\u00eda un bal\u00f3n a Montalb\u00e1n que pon\u00eda el 0-1, gol que ser\u00eda anulado por un fuera de juego inexistente, siete minutos despu\u00e9s, en el 23 y tras una falta colada desde su propio campo, el delantero de los locales ganaba el salto al defensa colomense y de cabeza hacia el 1-0. La reacci\u00f3n de los azules fue buena y pronto empezaron a generar ocasiones buscando el empate, empate que llegar\u00eda en el minuto 37 con un cabezazo de Lucas a la salida de un c\u00f3rner. Con este resultado se llegar\u00eda al descanso.<br \/>\nEn la reanudaci\u00f3n una Grama mucho mejor plantada buscaba incisivamente la victoria, \u00c1ngel, Montalban y Bruno, con un disparo al larguero, dispusieron de tres claras ocasiones para poner a los visitantes por delante en el marcador. Pero iba a ser el conjunto de Badalona quien tras una falta en la frontal y con un golpeo magistral, hac\u00eda el 2-1. Momentos de desconcierto de nuestro Juvenil, que aprovech\u00f3 el Llefia para tener una ocasi\u00f3n de hacer el tercer gol, pero esta estuvo bien atajada por Nofu. En el minuto 72 y tras una jugada afortunada Montalban pon\u00eda las tablas en el marcador, 2-2. Es aqu\u00ed cuando los colomenses buscaron la victoria que al final no pudieron conseguir.<br \/>\nManu Pel\u00e1ez ; estoy orgulloso de mis jugadores, tienen muchas ganas de conseguir los objetivos, entrenan al 200% y lo han intentado hasta el final. Ya solo pensamos en volver el Martes al trabajo para preparar el partido ante Cornell\u00e1.<\/p>\n<p><strong>Juvenil B:<\/strong><\/p>\n<p>Partit molt molt complicat contra un rival f\u00edsicament molt superior, un rival que estreny en totes les l\u00ednies, ens costa molt combinar, per\u00f2 quan ho fem tenim perill a l&#8217;\u00e0rea rival, molt joc aeri en el qual no estem habituats, per\u00f2 una combinaci\u00f3 r\u00e0pida ens avan\u00e7a amb un gol de cap.<br \/>\nEl rival segueix estrenyent i ens tanca enrere amb alguna sortida fins que arriba el gol de l&#8217;empat.<br \/>\nUna segona part en qu\u00e8 els canvis intenten aportar el seu treball sense encert, qualsevol dels dos equips a estat a punt de portar-se els tres punts, per\u00f2 crec que vam guanyar un i no vam perdre dos.<br \/>\nNing\u00fa va dir que seria f\u00e0cil, la q\u00fcesti\u00f3 \u00e9s ser-hi donant guerra.<\/p>\n<p>Partido muy muy complicado contra un rival f\u00edsicamente muy superior, un rival que aprieta en todas las l\u00edneas, nos cuesta mucho combinar, pero cuando lo hacemos tenemos peligro en el \u00e1rea rival, mucho juego a\u00e9reo en el cual no estamos habituados, pero una combinaci\u00f3n r\u00e1pida nos adelanta con un gol de cabeza.<br \/>\nEl rival sigue apretando y nos encierra atr\u00e1s con alguna salida hasta que llega el gol del empate.<br \/>\nUna segunda parte en que los cambios intentan aportar su trabajo sin acierto, cualquiera de los dos equipos a estado apunto de llevarse los tres puntos, pero creo que ganamos uno y no perdimos dos.<br \/>\nNadie dijo que ser\u00eda f\u00e1cil, la cuesti\u00f3n es estar ah\u00ed dando guerra.<\/p>\n<p><strong>Juvenil C:<\/strong><\/p>\n<p>JC 1-0 JUPITER<br \/>\nBon partit del Juvenil C que va comen\u00e7ar dominant i amb aix\u00f2 despr\u00e9s de fer una bona pressi\u00f3 a la sortida de pilota del Jupiter la Fundaci\u00f3 es posava per davant en el marcador, a partir d&#8217;aqu\u00ed la Fundaci\u00f3 va poder marcar en diverses ocasioni per\u00f2 no ho va fer i era llavors quan el Jupiter tenia la millors ocasions per empatar per\u00f2 el resultat al descans va ser de 1-0. A la segona part el Jupiter va sortir a remuntar el partit per\u00f2 no era capa\u00e7 d&#8217;encertar de cara a porteria i la Fundaci\u00f3 sortia a la contra i feia el mateix, no era capa\u00e7 de sentenciar, al final el resultat no es va moure i la Fundaci\u00f3 es feia amb la vict\u00f2ria. 1-0<\/p>\n<p>JC 1-0 JUPITER<br \/>\nBuen partido del Juvenil C que empez\u00f3 dominando y con ello tras hacer una buena presi\u00f3n en la salida de bal\u00f3n del Jupiter la Fundaci\u00f3n se pon\u00eda por delante en el marcador, a partir de ah\u00ed la Fundaci\u00f3n pudo marcar en varias ocasione pero no lo hizo y era entonces cuando el Jupiter tenia la mejores ocasiones para empatar pero el resultado al descanso fue de 1-0. En la segunda parte el Jupiter sali\u00f3 a remontar el partido pero no era capaz de acertar de cara a porter\u00eda y la Fundaci\u00f3n sal\u00eda a la contra y hac\u00eda lo mismo, no era capaz de sentenciar, al final el resultado no se movi\u00f3 y la Fundaci\u00f3n se hac\u00eda con la victoria. 1-0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juvenil A: Unificacion Llefia 2 JA 2 El Juvenil A treu un punt d&#8217;un camp complicat com \u00e9s el del Llefi\u00e0, punt que despr\u00e9s de la derrota de l&#8217;Sants pot fer-ho bo la propera jornada a Cornell\u00e0. El partit va comen\u00e7ar amb la Fundaci\u00f3 molt ficada i un Llefi\u00e0 molt agressiu en el joc a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":26395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[],"class_list":["post-26491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-juvenils"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=26491"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26491\/revisions"}],"predecessor-version":[{"id":26492,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26491\/revisions\/26492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/26395"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=26491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=26491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=26491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}