{"id":26013,"date":"2018-12-28T10:55:30","date_gmt":"2018-12-28T09:55:30","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=26013"},"modified":"2018-12-30T11:45:01","modified_gmt":"2018-12-30T10:45:01","slug":"canvi-a-la-porteria-de-la-grama-adeu-texeira-benvingut-priego","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/canvi-a-la-porteria-de-la-grama-adeu-texeira-benvingut-priego\/","title":{"rendered":"Canvi a la porteria de la Grama: Ad\u00e9u Texeira, benvingut Priego. (SANTS INNOCENTS 2018)"},"content":{"rendered":"<figure id=\"attachment_26014\" aria-describedby=\"caption-attachment-26014\" style=\"width: 688px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/12\/porteros.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26014 \" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/12\/porteros.png\" alt=\"\" width=\"688\" height=\"656\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/12\/porteros.png 942w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/12\/porteros-300x286.png 300w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/12\/porteros-768x732.png 768w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/a><figcaption id=\"caption-attachment-26014\" class=\"wp-caption-text\">A l&#8217;esquerra: Marc Priego amb l&#8217;Europa. A la dreta: Toni Texeira amb la Grama.<\/figcaption><\/figure>\n<h3>Mat\u00ed mogut a les oficines de la Fundaci\u00f3 Esportiva Grama. El que a la tarda d\u2019ahir era un \u201crun-run\u201d s\u2019ha confirmat aquest mat\u00ed amb la baixa oficial de Toni Texeira com a jugador de l\u2019entitat colomenca.<\/h3>\n<p>Despr\u00e9s de la seva supl\u00e8ncia el passat diumenge contra l\u2019E.C. Granollers, el porter potablava s\u2019ha mostrat molt descontent durant la setmana i va demanar, personalment al President, que li deix\u00e9s marxar abans de que es reinici\u00ef la lliga de Tercera Divisi\u00f3 el proper 6 de gener.<\/p>\n<p>Des de la Fundaci\u00f3 Esportiva Grama, que sempre ha tractat a Texeira com el gran porter que \u00e9s, s\u2019ha estudiat la possibilitat de permetre la seva marxa. Finalment, l\u2019\u00c0rea esportiva encap\u00e7alada per Manolo Garc\u00eda i amb l\u2019aprovaci\u00f3 del cos t\u00e8cnic, ha accedit a concedir-li la baixa amb la condici\u00f3 de poder cobrir el seu lloc, pr\u00e8viament,\u00a0 amb un porter de garanties.<\/p>\n<p>El C.E. Europa, Entitat que ja pretenia a Texeira aquest estiu, ser\u00e0 el nou dest\u00ed del porter pratenc. Despr\u00e9s d\u2019arribar a un acord entre Directives, la Fundaci\u00f3 Esportiva Grama incorporar\u00e0 al porter escapulat MARC PRIEGO (05\/07\/1996) fins a final de temporada amb opci\u00f3 d\u2019una m\u00e9s si l\u2019equip compleix objectius.<\/p>\n<p>Format al futbol base de la U.E. Sant Andreu, despr\u00e9s de debutar com a s\u00e8nior al Masnou i tornar a Sant Andreu per defensar la porteria quadribarrada durant dos temporades, Priego, va arribar aquest estiu al C.E. Europa. Ha jugat 20 partits i ha encaixat 22 gols. Deixa l\u2019equip de Gr\u00e0cia situat a la novena posici\u00f3 amb 31 punts.<\/p>\n<p>Amb aquest comunicat oficial, la nostra Entitat vol agrair enormement a Toni Texeira els bons moments que ens ha fet passar defensant la nostra porteria i, a m\u00e9s, volem donar una sonora benvinguda a Marc Priego desitjant-li molta sort en la seva etapa a la Grama.<\/p>\n<p>Ad\u00e9u Texeira, benvingut Priego.<\/p>\n<p>[divider]<\/p>\n<h3>Ma\u00f1ana movida en las oficinas de la Fundaci\u00f3 Esportiva Grama. Lo que en la tarde de ayer era un \u00abrun-run\u00bb se ha confirmado esta ma\u00f1ana con la baja oficial de Toni Texeira como jugador de la entidad colomense.<\/h3>\n<p>Tras su suplencia el pasado domingo contra el E.C. Granollers, el portero potablava se ha mostrado muy descontento durante la semana y pidi\u00f3, personalmente al Presidente, que le dejara marchar antes de que se reinicie la liga de Tercera Divisi\u00f3n el pr\u00f3ximo 6 de enero.<\/p>\n<p>Desde la Fundaci\u00f3 Esportiva Grama, que siempre ha tratado a Texeira como el gran portero que es, se ha estudiado la posibilidad de permitir su marcha. Finalmente, el \u00c1rea deportiva encabezada por Manolo Garc\u00eda y con la aprobaci\u00f3n del cuerpo t\u00e9cnico, ha accedido a concederle la baja con la condici\u00f3n de poder cubrir su lugar, previamente, con un portero de garant\u00edas.<\/p>\n<p>El C.E. Europa, Entidad que ya pretend\u00eda a Texeira este verano, ser\u00e1 el nuevo destino del portero pratense. Tras llegar a un acuerdo entre Directivas, la Fundaci\u00f3 Esportiva Grama incorporar\u00e1 al portero escapulado MARC PRIEGO (07\/05\/1996) hasta final de temporada con opci\u00f3n de una m\u00e1s si el equipo cumple objetivos.<\/p>\n<p>Formado en el f\u00fatbol base de la U.E. San Andreu, tras debutar como senior en el Masnou y volver a San Andreu para defender la porter\u00eda cuatribarrada durante dos temporadas, Priego, lleg\u00f3 este verano al C.E. Europa. Ha jugado 20 partidos y ha encajado 22 goles. Deja el equipo de Gracia situado en la novena posici\u00f3n con 31 puntos.<\/p>\n<p>Con este comunicado oficial, nuestra Entidad quiere agradecer enormemente a Toni Texeira los buenos momentos que nos ha hecho pasar defendiendo nuestra porter\u00eda y, adem\u00e1s, queremos dar una sonora bienvenida a Marc Priego dese\u00e1ndole mucha suerte en su etapa en la grama.<\/p>\n<p>Adi\u00f3s Texeira, bienvenido Priego.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat\u00ed mogut a les oficines de la Fundaci\u00f3 Esportiva Grama. El que a la tarda d\u2019ahir era un \u201crun-run\u201d s\u2019ha confirmat aquest mat\u00ed amb la baixa oficial de Toni Texeira com a jugador de l\u2019entitat colomenca. Despr\u00e9s de la seva supl\u00e8ncia el passat diumenge contra l\u2019E.C. Granollers, el porter potablava s\u2019ha mostrat molt descontent durant [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":26014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1240,1238,24,1239,1237],"class_list":["post-26013","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-baja-portero","tag-c-e-europa","tag-fundacio-esportiva-grama","tag-intercambio","tag-toni-texeira-marc-priego"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=26013"}],"version-history":[{"count":3,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26013\/revisions"}],"predecessor-version":[{"id":26024,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/26013\/revisions\/26024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/26014"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=26013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=26013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=26013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}