{"id":24600,"date":"2018-05-22T21:36:44","date_gmt":"2018-05-22T20:36:44","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=24600"},"modified":"2018-05-22T21:36:44","modified_gmt":"2018-05-22T20:36:44","slug":"ultim-partit-de-lliga-comiat-a-casa","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/ultim-partit-de-lliga-comiat-a-casa\/","title":{"rendered":"\u00daltim partit de lliga, comiat a casa"},"content":{"rendered":"<p>El conjunt dirigit per<strong> Jos\u00e9 Antonio Garc\u00eda Escribano<\/strong> s&#8217;acomiada de Primera Catalana a casa. Els colomencs volen acomiadar aquesta gran temporada amb una vict\u00f2ria davant la seva afici\u00f3.<\/p>\n<p style=\"text-align: center;\"><strong>Diumenge a les 12 hores al Municipal de la Grama.<\/strong><\/p>\n<p>El seu rival ser\u00e0 el <strong>CE Farners<\/strong>, sis\u00e8 classificat de la lliga amb 50 punts. Tenen la possibilitat d&#8217;acabar en quarta posici\u00f3. Porten dues jornades seguides sense perdre.<\/p>\n<p><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/05\/DdFoQcSXUAA-Gte.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-24424\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/05\/DdFoQcSXUAA-Gte-1024x768.jpg\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/05\/DdFoQcSXUAA-Gte.jpg 1024w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/05\/DdFoQcSXUAA-Gte-300x225.jpg 300w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2018\/05\/DdFoQcSXUAA-Gte-768x576.jpg 768w\" alt=\"\" width=\"618\" height=\"464\" \/><\/a><\/p>\n<p>El conjunto dirigido por<strong>\u00a0Jos\u00e9 Antonio Garc\u00eda Escribano<\/strong>\u00a0se despide de Primera Catalana en casa. Los colomenses quieren despedir esta gran temporada con una victoria ante su afici\u00f3n.<\/p>\n<p style=\"text-align: center;\"><strong>El domingo a las 12 horas en el Municipal de la Grama.<\/strong><\/p>\n<p>Su rival ser\u00e1 el\u00a0<b>CE Farners<\/b>, sexto clasificado de la liga con 50 puntos. Tienen la posibilidad de terminar en cuarta posici\u00f3n. Llevan dos jornadas seguidas sin perder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conjunt dirigit per Jos\u00e9 Antonio Garc\u00eda Escribano s&#8217;acomiada de Primera Catalana a casa. Els colomencs volen acomiadar aquesta gran temporada amb una vict\u00f2ria davant la seva afici\u00f3. Diumenge a les 12 hores al Municipal de la Grama. El seu rival ser\u00e0 el CE Farners, sis\u00e8 classificat de la lliga amb 50 punts. Tenen la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":24424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[1171,24,320,1145,1151],"class_list":["post-24600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-primer-equip","tag-ce-farners","tag-fundacio-esportiva-grama","tag-grama","tag-municipal-de-la-grama","tag-primera-catalana"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/24600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=24600"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/24600\/revisions"}],"predecessor-version":[{"id":24601,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/24600\/revisions\/24601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/24424"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=24600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=24600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=24600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}