{"id":2439,"date":"2014-03-07T07:25:41","date_gmt":"2014-03-07T06:25:41","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2439"},"modified":"2014-03-06T22:57:45","modified_gmt":"2014-03-06T21:57:45","slug":"el-juvenil-a-de-la-fegrama-es-desplacara-diumenge-al-municipal-de-santa-eulalia-de-lhospitalet","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-juvenil-a-de-la-fegrama-es-desplacara-diumenge-al-municipal-de-santa-eulalia-de-lhospitalet\/","title":{"rendered":"El Juvenil A de la FEGrama es despla\u00e7ar\u00e0 diumenge al Municipal de Santa Eul\u00e0lia de L&#8217;Hospitalet"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El\u00a0<strong>Juvenil Preferent de la FEGrama<\/strong>\u00a0sortir\u00e0 molt mentalitzat despr\u00e8s de la derrota als \u00faltims minuts del partit contra el\u00a0<strong>Sant Ignasi<\/strong>\u00a0per un ajustat 1-2 just la setmana abans dels descans de Carnestoltes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Els jugadors de Santa Coloma entrenats per\u00a0<strong>Toni Rovira i Ismael Poveda<\/strong>\u00a0encaix\u00e0 la segona derrota consecutiva, fet que just el Sant Ignasi aprofit\u00e0 per acostar-se a un punt, 26. L&#8217;equip de la Fundaci\u00f3 Grama no ha perdut el lloc nov\u00e8 de la classificaci\u00f3 a aquesta jornada 20 del grup 4.<\/span><\/p>\n<p>[divider]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NFG_CmpJornada?cod_primaria=1000120&amp;CodCompeticion=18473287&amp;CodGrupo=18491079&amp;CodTemporada=9&amp;CodJornada=12&#8243; target=\u00bbblank\u00bb ]Resultats[\/button]<\/p>\n<p>[button color=\u00bbblue\u00bb size=\u00bbsmall\u00bb link=\u00bbhttp:\/\/www.fcf.cat\/pnfg\/NPcd\/NFG_VisClasificacion?cod_primaria=1000120&amp;codgrupo=18491079&amp;codcompeticion=18473287&#8243; target=\u00bbblank\u00bb ]Classificaci\u00f3[\/button]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la seg\u00fcent jornada despr\u00e8s de Carnestoltes ser\u00e0 contra el\u00a0<strong>Santa Eul\u00e0lia<\/strong>, dotz\u00e8 amb 23 punts, quatre menys que els de la\u00a0<strong>Fundaci\u00f3 Grama.<\/strong>\u00a0Aix\u00ed que segur ser\u00e0 un partit amb molts al.licients per amb\u00f2s conjunts per seguir pujant a la taula a la jornada 21, al <strong>Municipal de Santa Eul\u00e0lia de L&#8217;Hospitalet<\/strong> el diumenge 9 de mar\u00e7 des de les 13 hores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El Juvenil Preferente de la FEGRAMa saldr\u00e1 muy mentalizado despu\u00e9s de la derrota en los \u00faltimos minutos del partido contra el San Ignacio por un ajustado 1-2 justo la semana antes del descanso de Carnaval.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los jugadores de Santa Coloma entrenados por Toni Rovira y Ismael Poveda encaj\u00f3 la segunda derrota consecutiva, lo que justo el San Ignacio aprovech\u00f3 para acercarse a un punto, 26. El equipo de la Fundaci\u00f3n Grama no ha perdido el puesto noveno de la clasificaci\u00f3n a esta jornada 20 del grupo 4. <\/span><\/p>\n<p><span style=\"color: #000000;\">En la siguiente jornada despu\u00e9s de Carnaval ser\u00e1 contra el Santa Eulalia, duod\u00e9cimo con 23 puntos, cuatro menos que los de la Fundaci\u00f3n Grama. As\u00ed que seguro ser\u00e1 un partido con muchos alicientes para \u00e1mbos conjuntos para seguir subiendo en la tabla en la jornada 21, en el Municipal de Santa Eulalia de L&#8217;Hospitalet el domingo 9 de marzo desde las 13 horas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Juvenil Preferent de la FEGrama\u00a0sortir\u00e0 molt mentalitzat despr\u00e8s de la derrota als \u00faltims minuts del partit contra el\u00a0Sant Ignasi\u00a0per un ajustat 1-2 just la setmana abans dels descans de Carnestoltes. Els jugadors de Santa Coloma entrenats per\u00a0Toni Rovira i Ismael Poveda\u00a0encaix\u00e0 la segona derrota consecutiva, fet que just el Sant Ignasi aprofit\u00e0 per acostar-se a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[19,20,557,556,27,21],"class_list":["post-2439","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-juvenils","tag-feg","tag-fundacio-grama","tag-hospitalet","tag-municipal-de-santa-eulalia-de-lhospitalet","tag-nou-municipal","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2439"}],"version-history":[{"count":3,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2439\/revisions"}],"predecessor-version":[{"id":2486,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2439\/revisions\/2486"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}