{"id":2343,"date":"2014-02-24T07:54:36","date_gmt":"2014-02-24T06:54:36","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2343"},"modified":"2014-03-06T22:45:27","modified_gmt":"2014-03-06T21:45:27","slug":"el-lider-derrota-al-benjami-c-de-la-fegrama-cinque-classificat","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-lider-derrota-al-benjami-c-de-la-fegrama-cinque-classificat\/","title":{"rendered":"El l\u00edder derrota al Benjam\u00ed C de la FEGrama, cinqu\u00e8 classificat"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El l\u00edder derrota al Benjam\u00ed C de la FEGrama. Els de <strong>La Florida<\/strong> fiquen un 1-9 als de la <strong>Fundaci\u00f3 Grama<\/strong> encara que segueixen a una bona cinquena posici\u00f3 del grup 3.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El solitari gol de <strong>Juan Cort\u00e9s<\/strong> va ser el de l&#8217;honor davant un l\u00edder al qual el sortia tot al Nou Municipal de Santa Coloma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la jornada 19 despr\u00e8s del descans pertinent de Carnestoltes, el conjunt de la FEG dirigit per <strong>Lautaro Rosales<\/strong> viatjar\u00e0 al camp del <strong>Carmelo<\/strong>, set\u00e8 amb 28 punts nom\u00e8s cinc punts menys que els de Santa Coloma, el dissabte 8 de mar\u00e7 a les 10 del mat\u00ed al <strong>Complex Esportiu Municipal Carmel<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Al\u00e9 Grama!!!<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El l\u00edder derrota al Benjam\u00edn C de la FEGRAM. Los de La Florida meten un 1-9 a los de la Fundaci\u00f3n Grama que siguen a una buena quinta posici\u00f3n del grupo 3.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El solitario gol de Juan Cort\u00e9s fue el del honor ante un l\u00edder al que el sal\u00eda todo el Nou Municipal de Santa Coloma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la jornada 19 despu\u00e9s del descanso pertinente de Carnaval, el conjunto de la FEG viajar\u00e1 al campo del Carmelo, s\u00e9ptimo con 28 puntos s\u00f3lo cinco puntos menos que los de Santa Coloma, el s\u00e1bado 8 de marzo en el Complejo Deportivo Municipal Carmel.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El l\u00edder derrota al Benjam\u00ed C de la FEGrama. Els de La Florida fiquen un 1-9 als de la Fundaci\u00f3 Grama encara que segueixen a una bona cinquena posici\u00f3 del grup 3. El solitari gol de Juan Cort\u00e9s va ser el de l&#8217;honor davant un l\u00edder al qual el sortia tot al Nou Municipal de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[251,539,20,27,166,21],"class_list":["post-2343","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-benjamins","tag-carmelo","tag-complex-esportiu-municipal-carmel","tag-fundacio-grama","tag-nou-municipal","tag-nou-municipal-de-santa-coloma-de-gramenet","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2343"}],"version-history":[{"count":3,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2343\/revisions"}],"predecessor-version":[{"id":2478,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2343\/revisions\/2478"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}