{"id":2308,"date":"2014-02-24T07:53:46","date_gmt":"2014-02-24T06:53:46","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2308"},"modified":"2014-02-23T22:12:11","modified_gmt":"2014-02-23T21:12:11","slug":"primera-derrota-de-la-temporada-del-cadet-b-de-la-fegrama-contra-el-sarria-per-2-3","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/primera-derrota-de-la-temporada-del-cadet-b-de-la-fegrama-contra-el-sarria-per-2-3\/","title":{"rendered":"Primera derrota de la temporada del Cadet B de la FEGrama contra el Sarri\u00e0 per 2-3"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La primera derrota de la temporada del <strong>Cadet B de la FEGrama<\/strong> ha caigut com una gerra d&#8217;aigua freda a uns jugadors que trenquen r\u00e8cords com els de gols a favor amb 70 i l&#8217;equip menys golejat tamb\u00e9 amb nom\u00e8s 14.<\/span><\/p>\n<figure id=\"attachment_2312\" aria-describedby=\"caption-attachment-2312\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2312 \" alt=\"Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomas.jpg\" width=\"510\" height=\"341\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomas.jpg 850w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomas-300x200.jpg 300w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomas-290x195.jpg 290w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/a><figcaption id=\"caption-attachment-2312\" class=\"wp-caption-text\">Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El conjunt dirigit per <strong>\u00c0lex Abril<\/strong> va comen\u00e7ar anant darrera amb el marcador del Nou Municipal encaixant un primer gol a la primera mitja hora de partit. Als tres minuts despr\u00e8s,<strong> Juan Santiago<\/strong> empatava el partit per\u00f2 de nou els de <strong>Sarri\u00e0<\/strong> s&#8217;adelantaven per dues vegades on 1-3 seria aventatja dificil de superar.<\/span><\/p>\n<figure id=\"attachment_2310\" aria-describedby=\"caption-attachment-2310\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomasAGARRON.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2310 \" alt=\"Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomasAGARRON.jpg\" width=\"510\" height=\"285\" \/><\/a><figcaption id=\"caption-attachment-2310\" class=\"wp-caption-text\">Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El 2-3 de <strong>Marc Arreciado<\/strong> al minut 73 va animar als jugadors de la Fundaci\u00f3 Grama que encara m\u00e9s va continuar apretant els punys per\u00f2 aquest cop el gol no va voler entrar.<\/span><\/p>\n<figure id=\"attachment_2311\" aria-describedby=\"caption-attachment-2311\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomasSERGIO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2311 \" alt=\"Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/02\/primeraderrotacadeteBsergiomasSERGIO.jpg\" width=\"510\" height=\"341\" \/><\/a><figcaption id=\"caption-attachment-2311\" class=\"wp-caption-text\">Fotos del Cadet B FEgrama cedides per Sergio M\u00e1s Navarro contra el Sarri\u00e0<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Com diuen que a les derrotes s&#8217;apren m\u00e9s que a les vict\u00f2ries, amb aquesta \u00fanica de moment en 18 jornades, a la 19 tocar\u00e0 un rival molt assequible com el pen\u00faltim, el <strong>Can Buxeres al seu Municipal Can Buxeres<\/strong> el dissabte 8 de mar\u00e7 des de les 14 hores.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">M\u00e9s que mai&#8230;Al\u00e9 Grama!!!<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La primera derrota de la temporada del Cadete B de la FEGRAMa ha ca\u00eddo como un jarro de agua fr\u00eda a unos jugadores que rompen r\u00e9cords como los de goles a favor con 70 y el equipo menos goleado tambi\u00e9n con s\u00f3lo 14.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El conjunto dirigido por Alex Abril empez\u00f3 yendo detr\u00e1s con el marcador del Nou Municipal encajando un primer gol en la primera media hora de partido. A los tres minutos despu\u00e9s, Juan Santiago empataba el partido pero de nuevo los de Sarri\u00e0 adelanta por dos veces en 1-3 ser\u00eda aventaja dificil de superar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El 2-3 de Marc Arreciado el minuto 73 anim\u00f3 a los jugadores de la Fundaci\u00f3n Grama que a\u00fan continu\u00f3 apretando los pu\u00f1os pero esta vez el gol no quiso entrar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Como dicen que las derrotas se aprende m\u00e1s que en las victorias, con esta \u00fanica de momento en 18 jornadas, en la 19 tocar\u00e1 un rival muy asequible como el pen\u00faltimo, el Can Buxeres en su Municipal Can Buxeres el s\u00e1bado 8 de marzo diciembre de las 14 horas.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Fotos cedides per Sergio M\u00e1s Navarro<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera derrota de la temporada del Cadet B de la FEGrama ha caigut com una gerra d&#8217;aigua freda a uns jugadors que trenquen r\u00e8cords com els de gols a favor amb 70 i l&#8217;equip menys golejat tamb\u00e9 amb nom\u00e8s 14. El conjunt dirigit per \u00c0lex Abril va comen\u00e7ar anant darrera amb el marcador del [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[533,20,534,27,166,21,83],"class_list":["post-2308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-cadets","tag-can-buxeres","tag-fundacio-grama","tag-municipal-can-buxeres","tag-nou-municipal","tag-nou-municipal-de-santa-coloma-de-gramenet","tag-santa-coloma","tag-sarria"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2308"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2308\/revisions"}],"predecessor-version":[{"id":2313,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2308\/revisions\/2313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/2312"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}