{"id":2257,"date":"2014-02-21T07:54:38","date_gmt":"2014-02-21T06:54:38","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2257"},"modified":"2014-02-20T20:57:10","modified_gmt":"2014-02-20T19:57:10","slug":"el-benjami-a-de-la-f-e-grama-voldra-sumar-a-casa-del-cuer-sistrells","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-benjami-a-de-la-f-e-grama-voldra-sumar-a-casa-del-cuer-sistrells\/","title":{"rendered":"El Benjam\u00ed A de la F.E. Grama voldr\u00e0 sumar a casa del cuer Sistrells"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Despr\u00e8s de la contundent vict\u00f2ria a casa del cinqu\u00e8 classificat, el\u00a0<strong>Vila Ol\u00edmpica Club Esportiu, el Benjam\u00ed A de la Fundaci\u00f3 Grama<\/strong>\u00a0ha tornat a realitzar un partit perfecte i\u00a0golejar a l\u2019<strong>Escola \u00c1ngel Pedraza <\/strong>per 17 gols a 0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Els jugadors de la Fundaci\u00f3 Grama voldran seguir marcant hist\u00f2ria al futbol a casa del\u00a0<strong>Sistrells<\/strong>, cuer de la classificaci\u00f3, a la\u00a0<strong>Zona Esportiva Can Cabanyes,<\/strong>\u00a0el pr\u00f2xim dissabte 22 de febrer a les 9 hores del mat\u00ed.<\/span><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Despu\u00e9s de la contundente victoria en casa del quinto clasificado, el Vila Ol\u00edmpica Club Deportivo, el Benjam\u00edn A de la Fundaci\u00f3n Grama ha vuelto a realizar un partido perfecto y golear en la Escuela \u00c1ngel Pedraza por 17 goles a 0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los jugadores de la Fundaci\u00f3n Grama querr\u00e1n seguir marcando historia en el f\u00fatbol casa del Sistrells, colista de la clasificaci\u00f3n, en la Zona Deportiva Can Cabanyes, el pr\u00f3ximo s\u00e1bado 22 de febrero a las 9 horas de la ma\u00f1ana.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e8s de la contundent vict\u00f2ria a casa del cinqu\u00e8 classificat, el\u00a0Vila Ol\u00edmpica Club Esportiu, el Benjam\u00ed A de la Fundaci\u00f3 Grama\u00a0ha tornat a realitzar un partit perfecte i\u00a0golejar a l\u2019Escola \u00c1ngel Pedraza per 17 gols a 0. Els jugadors de la Fundaci\u00f3 Grama voldran seguir marcant hist\u00f2ria al futbol a casa del\u00a0Sistrells, cuer de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[407,20,27,21,475],"class_list":["post-2257","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-benjamins","tag-escola-angel-pedraza","tag-fundacio-grama","tag-nou-municipal","tag-santa-coloma","tag-sistrells"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2257"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2257\/revisions"}],"predecessor-version":[{"id":2259,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2257\/revisions\/2259"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}