{"id":21821,"date":"2017-10-08T23:00:39","date_gmt":"2017-10-08T22:00:39","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=21821"},"modified":"2017-10-08T23:01:13","modified_gmt":"2017-10-08T22:01:13","slug":"golejada-de-linfantil-a-al-seu-debut","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/golejada-de-linfantil-a-al-seu-debut\/","title":{"rendered":"Golejada de l&#8217;Infantil A al seu debut"},"content":{"rendered":"<p>L&#8217;Infantil A va guanyar 0-7 a la UD Cornell\u00e0 E. Va ser per a la Fundaci\u00f3 el primer partit de lligada despr\u00e9s d&#8217;haver de ser susp\u00e8s la setmana passada el seu partit a causa del refer\u00e8ndum (partit que jugaran dimecres).<\/p>\n<p>La primera part va acabar amb un resultat de 0-1. Forta pressi\u00f3 molt alta de l&#8217;equip local per\u00f2 gr\u00e0cies al bon joc de la Grama i la bona circulaci\u00f3 de pilota van impedir que el Cornell\u00e0tuviese la pilota i pogu\u00e9s causar algun tipus de perill. A la segona meitat despr\u00e9s de perdonar molt en la primera la pilota va entrar a la porteria amb m\u00e9s facilitat.<\/p>\n<p>Quatres gols d&#8217;Ian, i un de Cristi\u00e1n, Izan i Moha van donar la primera golejada de la temporada a l&#8217;equip.<\/p>\n<p>[divider]<\/p>\n<p>El Infantil A gan\u00f3 0-7 a la UD Cornell\u00e0 E. Fue para la Fundaci\u00f3 el primer partido de ligada despu\u00e9s de tener que ser suspendido la semana pasada su partido a causa del refer\u00e9ndum (partido que jugar\u00e1n el mi\u00e9rcoles).<\/p>\n<p>La primera parte termin\u00f3 con un resultado de 0-1. Fuerte presi\u00f3n muy alta del equipo local pero gracias al buen juego de la Grama y la buena circulaci\u00f3n de bal\u00f3n impidieron que el Cornell\u00e0tuviese el bal\u00f3n y pudiese causar alg\u00fan tipo de peligro. En la segunda mitad despu\u00e9s de perdonar mucho en la primera el bal\u00f3n entr\u00f3 en la porter\u00eda con m\u00e1s facilidad.<\/p>\n<p>Cuatros goles de Ian, y uno de Cristi\u00e1n, Izan y Moha dieron la primera goleada de la temporada al equipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Infantil A va guanyar 0-7 a la UD Cornell\u00e0 E. Va ser per a la Fundaci\u00f3 el primer partit de lligada despr\u00e9s d&#8217;haver de ser susp\u00e8s la setmana passada el seu partit a causa del refer\u00e8ndum (partit que jugaran dimecres). La primera part va acabar amb un resultat de 0-1. Forta pressi\u00f3 molt alta de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[24],"class_list":["post-21821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-infantils","tag-fundacio-esportiva-grama"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/21821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=21821"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/21821\/revisions"}],"predecessor-version":[{"id":21823,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/21821\/revisions\/21823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=21821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=21821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=21821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}