{"id":2146,"date":"2014-02-17T08:32:34","date_gmt":"2014-02-17T07:32:34","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2146"},"modified":"2014-02-19T18:55:31","modified_gmt":"2014-02-19T17:55:31","slug":"el-doblet-de-gols-deiker-del-benjami-d-de-la-f-e-grama-a-punt-de-remuntar-enfront-el-lider-lescola-brafa-2-3","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-doblet-de-gols-deiker-del-benjami-d-de-la-f-e-grama-a-punt-de-remuntar-enfront-el-lider-lescola-brafa-2-3\/","title":{"rendered":"El doblet de gols de&#8217;Iker del Benjam\u00ed D de la F.E. Grama a punt de remuntar enfront el l\u00edder, l\u2019Escola Brafa (2-3)"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El <strong>Benjam\u00ed D de la Fundaci\u00f3 Grama<\/strong> segueix al mig de la classificaci\u00f3 a la novena posici\u00f3 amb 25 punts malgrat i tot la derrota enfront el l\u00edder, l&#8217;<strong>Escola Brafa, per un ajustat 2-3<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Els entrenats per <strong>V\u00edctor D\u00edaz i\u00a0Ra\u00fal Ruiz <\/strong>van posar-ho tot davant la seva afici\u00f3 al <strong>Nou Municipal de Santa Coloma de Gramenet<\/strong> i encara que es van posar les coses molt complicades amb un parcial de 0-3, dos gols d&#8217;<strong>Iker Quintana<\/strong> van ficar la pressi\u00f3 i la il.lusi\u00f3 de fer una remuntada de les grans enfront el l\u00edder.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L&#8217;entrenador <strong>V\u00edctor D\u00edaz<\/strong> ha vist aix\u00ed el partit jugat aquesta setmana\u00a0entre el <strong>Benjam\u00edn D FEGrama 2-3 Escola Brafa<\/strong> A on diu que \u00abbuen partido de los ni\u00f1os con muy buena actitud y entrega contra el l\u00edder de la categor\u00eda,\u00a0siendo nosotros de primer a\u00f1o y ellos de segundo, a\u00fan as\u00ed les plantamos cara y perdimos por la m\u00ednima dando la talla\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No va poder ser finalment i ara els jugadors de la Fundaci\u00f3 Grama aniran molt motivats a la seg\u00fcent jornada 18 al <strong>Complex Esportiu La Guineueta davant l&#8217;Escola Esportiva Guineueta,<\/strong> tercer classificat amb 40 punts, el pr\u00f2xim dissabte 22 de febrer des de les 10:45 hores.<\/span><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El Benjam\u00edn D de la Fundaci\u00f3n Grama sigue en medio de la clasificaci\u00f3n en la novena posici\u00f3n con 25 puntos a pesar incluso de la derrota frente al l\u00edder, la Escuela Brafa, por un ajustado 2-3.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los entrenados por\u00a0<strong>V\u00edctor D\u00edaz i\u00a0Ra\u00fal Ruiz\u00a0<\/strong>pusieron todo ante su afici\u00f3n en el Nou Municipal de Santa Coloma y aunque se pusieron las cosas muy complicadas con un parcial de 0-3, dos goles de Iker Quintana metieron la presi\u00f3n y la ilusi\u00f3n de hacer una remontada de las grandes frente al l\u00edder.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El entrenador V\u00edctor D\u00edaz ha visto as\u00ed el partido jugado esta semana entre el Benjam\u00edn D FEGRAM 2-3 Escuela Brafa A donde dice que \u00abbuen partido de los ni\u00f1os con muy buena actitud y entrega contra el l\u00edder de la categor\u00eda, si\u00e9ndo nosotros de primer a\u00f1o y Ellos de Segundo, A\u00fan as\u00ed las plantamos cara y perdimos por la m\u00ednima Dando la talla \u00ab.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No pudo ser finalmente y ahora los jugadores de la Fundaci\u00f3n Grama ir\u00e1n muy motivados a la siguiente jornada 18 en el Complejo Deportivo La Guineueta ante la Escuela Deportiva Guineueta, tercer clasificado con 40 puntos, el pr\u00f3ximo s\u00e1bado 22 de febrero desde las 10: 45 horas.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Benjam\u00ed D de la Fundaci\u00f3 Grama segueix al mig de la classificaci\u00f3 a la novena posici\u00f3 amb 25 punts malgrat i tot la derrota enfront el l\u00edder, l&#8217;Escola Brafa, per un ajustat 2-3. Els entrenats per V\u00edctor D\u00edaz i\u00a0Ra\u00fal Ruiz van posar-ho tot davant la seva afici\u00f3 al Nou Municipal de Santa Coloma de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[477,500,355,19,20,499,130],"class_list":["post-2146","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-benjamins","tag-benjami-d-de-la-fundacio-grama","tag-complex-esportiu-la-guineueta","tag-escola-esportiva-guineueta","tag-feg","tag-fundacio-grama","tag-nou-municipal-santa-coloma","tag-santa-coloma-de-gramenet"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2146"}],"version-history":[{"count":4,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2146\/revisions"}],"predecessor-version":[{"id":2183,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2146\/revisions\/2183"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}