{"id":2143,"date":"2014-02-17T08:17:54","date_gmt":"2014-02-17T07:17:54","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2143"},"modified":"2014-02-17T08:17:54","modified_gmt":"2014-02-17T07:17:54","slug":"un-poquer-de-miguel-angel-i-tres-doblets-de-gols-de-david-juan-i-justin-del-benjami-c-de-la-f-e-grama-golegen-contra-el-zona-franca-per-11-1","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/un-poquer-de-miguel-angel-i-tres-doblets-de-gols-de-david-juan-i-justin-del-benjami-c-de-la-f-e-grama-golegen-contra-el-zona-franca-per-11-1\/","title":{"rendered":"Un p\u00f2quer de Miguel \u00c1ngel i tres doblets de gols de David, Juan i Justin del Benjam\u00ed C de la F.E Grama golegen contra el Zona Franca per 11-1"},"content":{"rendered":"<p itemprop=\"itemReviewed\" itemtype=\"http:\/\/schema.org\/Thing\" style=\"text-align: justify;\"><span style=\"color: #000000;\">La tercera vict\u00f2ria m\u00e9s un empat dels \u00faltims cinc resultats fan que el <strong>Benjam\u00ed C de la Fundaci\u00f3 Grama<\/strong> es consolidi cinqu\u00e8 classificat a aquest grup 3 de <strong>Tercera Divisi\u00f3<\/strong>.<\/span><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Els jugadors dirigits per <strong>Lautaro Rosales<\/strong> van golejar a casa davant la <strong>Zona Franca,<\/strong> catorz\u00e8 classificat, per un contundent 11-1.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tot i l&#8217;abultat resultat els primers minuts els jugadors visitants van empatar el primer gol de <strong>Justin Prieto<\/strong>, que faria despr\u00e8s doblet de gols.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Despr\u00e8s <strong>David Serra<\/strong> que tamb\u00e9 faria altra doblet de gols, el seguiria<strong> Juan Cort\u00e9s<\/strong> amb un altre doblet, i el p\u00f2quer de gols de <strong>Miguel \u00c1ngel Saiz<\/strong> per deixar el marcador definitiu de 11-1.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aquest triomf d\u00f3na molta confian\u00e7a per seguir sumant a la jornada 18 on toca enfrontarse al l\u00edder, <strong>La Florida, al Nou Municipal de Santa Coloma<\/strong> a les 11 hores del mat\u00ed del diumenge 23 de febrer.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u00c9s una clara oportunitat de veure si el l\u00edder pot punxar adem\u00e9s de l&#8217;\u00fanica derrota que te en 16 partits. Mentrestant, els jugadors de la Fundaci\u00f3 Grama van cinqu\u00e8 amb d\u00e9u vict\u00f2ries i faran tot lo possible perqu\u00e8 el Nou Municipal de <strong>Santa Coloma de Gramenet<\/strong> sigui un fort\u00ed inexpugnable.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La tercera victoria m\u00e1s un empate de los \u00faltimos cinco resultados hacen que el Benjam\u00edn C de la Fundaci\u00f3n Grama se consolide quinto clasificado en este grupo 3 de Tercera Divisi\u00f3n .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los jugadores dirigidos por Lautaro Rosales golearon en casa ante la Zona Franca , decimocuarto clasificado , por un contundente 11-1 .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aunque el abultado resultado los primeros minutos los jugadores visitantes empataron el primer gol de Justin Prieto , que har\u00eda despu\u00e9s doblete de goles .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Despu\u00e9s David Serra que tambi\u00e9n har\u00eda otra doblete de goles, el seguir\u00eda Juan Cort\u00e9s con otro doblete , y el p\u00f3quer de goles de Miguel \u00c1ngel Saiz para dejar el marcador definitivo de 11-1 .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Este triunfo da mucha confianza para seguir sumando a la jornada 18 donde toca enfrentarse al l\u00edder , La Florida , en el Nou Municipal de Santa Coloma a las 11 horas de la ma\u00f1ana del domingo 23 de febrero.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es una clara oportunidad de ver si el l\u00edder puede pinchar adem\u00e1s de la \u00fanica derrota que tiene en 16 partidos . Mientras tanto, los jugadores de la Fundaci\u00f3n Grama van quinto con dios victorias y har\u00e1n todo lo posible para que el Nou Municipal de Santa Coloma sea un fort\u00edn inexpugnable .<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La tercera vict\u00f2ria m\u00e9s un empat dels \u00faltims cinc resultats fan que el Benjam\u00ed C de la Fundaci\u00f3 Grama es consolidi cinqu\u00e8 classificat a aquest grup 3 de Tercera Divisi\u00f3. Els jugadors dirigits per Lautaro Rosales van golejar a casa davant la Zona Franca, catorz\u00e8 classificat, per un contundent 11-1. Tot i l&#8217;abultat resultat els [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[498,19,20,397,130,497],"class_list":["post-2143","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-benjamins","tag-al-nou-municipal-de-santa-coloma","tag-feg","tag-fundacio-grama","tag-la-florida","tag-santa-coloma-de-gramenet","tag-tercera-divisio"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"predecessor-version":[{"id":2145,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2143\/revisions\/2145"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}