{"id":2125,"date":"2014-02-17T07:23:17","date_gmt":"2014-02-17T06:23:17","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2125"},"modified":"2014-02-19T18:09:27","modified_gmt":"2014-02-19T17:09:27","slug":"lalevi-c-de-la-f-e-grama-no-perdona-al-cuer-lhospitalense-16-0","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/lalevi-c-de-la-f-e-grama-no-perdona-al-cuer-lhospitalense-16-0\/","title":{"rendered":"L\u2019Alev\u00ed C de la F.E. Grama no perdona al cuer, l\u2019Hospitalense (16-0)"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A punt de remuntar a casa de la<strong> Zona Franca<\/strong> (cinqu\u00e8 classificat) on finalment es va perdre per l\u2019ajustat 7-6, l\u2018<strong>Alev\u00ed C de la Fundaci\u00f3 Grama<\/strong> aprofita l\u2019ocasi\u00f3 d\u2019or a l\u2019enfrontament contra el cuer, l\u2019<strong>Hospitalense<\/strong>, i endosarlos una golejada de 16-0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La llauna de gols es va obrir des de el primer minut amb la realitzaci\u00f3 de <strong>Joel Rosa,<\/strong> seguir del de <strong>Jean Paul Medina<\/strong> al minut 3. Al minut 6 era el torn de marcar de <strong>Jos\u00e9 Orobio<\/strong>, que acabaria fent un <em>hattrick<\/em>, el mateix que Joel Rosa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Adam va marcar el 6-0, <strong>Edgar<\/strong> el 8-0, <strong>Eric Pueyo<\/strong> el 10-0 i <strong>Pau<\/strong> l&#8217;11-0. <strong>Emil<\/strong> el 13-0 i E<strong>duardo Chac\u00f3n<\/strong> realitzaria un doblet seguit, el 14 i 15-0. Va tancar el triplet de Joel Rosa deixant el definitiu 16-0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aix\u00ed resumeix les sensacions l&#8217;entrenador de l&#8217;Alev\u00ed C de la FEGrama,<strong> Jos\u00e9 Mar\u00eda Tiz\u00f3n:<\/strong> \u00abBuen partido del Alev\u00edn C FEGrama que gan\u00f3 al Hospitalense por 16-0, un resultado abultado pero buen juego por parte nuestra gracias al trabajo y al esfuerzo de los chicos durante la semana\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aquest triomf dels de la <strong>Fundaci\u00f3 Grama<\/strong> dirigits per <strong>Jos\u00e9 Mar\u00eda Tiz\u00f3n<\/strong> el fan pujar una posici\u00f3 fins a la onzena a la classificaci\u00f3 amb 16 punts de cinc vict\u00f2ries i un empat.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El<strong> Nou Municipal de Santa Coloma<\/strong> es va convertir en un basti\u00f3 el passat diumenge 16 de febrer on varen animar els socis i aficionats al futbol que van recolzr als joves jugadors de la <strong>Fundaci\u00f3 Esportiva Grama.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la jornada 18 toca l&#8217;enfrontament sup\u00ed a casa del l\u00edder, <strong>La Florida<\/strong>, amb 45 punts, el pr\u00f2xim dissabte 22 de febrer a les 12:30 hores al<strong> Municipal de La Florida.<\/strong><\/span><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A punto de remontar en casa de la Zona Franca ( quinto clasificado ) donde finalmente se perdi\u00f3 por el ajustado 7-6 , el Alev\u00edn C de la Fundaci\u00f3n Grama aprovecha la ocasi\u00f3n de oro en el enfrentamiento contra el colista , el Hospitalense , y endosarlos una goleada de 16-0 .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La lata de goles se abri\u00f3 desde el primer minuto con la realizaci\u00f3n de Joel Rosa , seguir el de Jean Paul Medina en el minuto 3 . En el minuto 6 era el turno de marcar de Jos\u00e9 Orobio , que terminar\u00eda haciendo un hattrick , lo mismo que Joel Rosa .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Adam marc\u00f3 el 6-0 , Edgar el 8-0 , Eric Pueyo el 10-0 y Paz del 11-0 . Emil el 13-0 y Eduardo Chac\u00f3n realizar\u00eda un doblete seguido, el 14 y 15-0 . Cerr\u00f3 el triplete de Joel Rosa dejando el definitivo 16-0 .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">As\u00ed resume las sensaciones del entrenador del Alev\u00edn C de la FEGRAM, Jos\u00e9 Mar\u00eda Tiz\u00f3n: \u00abBuen partido del Alev\u00edn C FEGRAM que gano al Hospitalense por 16-0, un Resultado abultada pero buen juego por Parte Nuestra gracias al Trabajo y al ESFUERZO de los chicos Durante la semana \u00ab.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Este triunfo de los de la Fundaci\u00f3n Grama dirigidos por Jos\u00e9 Mar\u00eda Tiz\u00f3n le hacen subir una posici\u00f3n hasta la und\u00e9cima en la clasificaci\u00f3n con 16 puntos de cinco victorias y un empate .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El Nou Municipal de Santa Coloma se convirti\u00f3 en un basti\u00f3n el pasado domingo 16 de febrero donde animaron a los socios y aficionados al f\u00fatbol que recolzr los j\u00f3venes jugadores de la Fundaci\u00f3n Deportiva Grama .<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A punt de remuntar a casa de la Zona Franca (cinqu\u00e8 classificat) on finalment es va perdre per l\u2019ajustat 7-6, l\u2018Alev\u00ed C de la Fundaci\u00f3 Grama aprofita l\u2019ocasi\u00f3 d\u2019or a l\u2019enfrontament contra el cuer, l\u2019Hospitalense, i endosarlos una golejada de 16-0. La llauna de gols es va obrir des de el primer minut amb la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,4],"tags":[19,20,155,397,494,55,21,474],"class_list":["post-2125","post","type-post","status-publish","format-standard","hentry","category-alevins","category-base-inclusiu","tag-feg","tag-fundacio-grama","tag-hospitalense","tag-la-florida","tag-municipal-de-la-florida","tag-nou-municipal-de-santa-coloma","tag-santa-coloma","tag-zona-franca"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2125"}],"version-history":[{"count":4,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2125\/revisions"}],"predecessor-version":[{"id":2181,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2125\/revisions\/2181"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}