{"id":2051,"date":"2014-02-14T07:56:03","date_gmt":"2014-02-14T06:56:03","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=2051"},"modified":"2014-02-13T23:06:24","modified_gmt":"2014-02-13T22:06:24","slug":"ocasio-dor-per-lalevi-c-de-la-f-e-grama-a-santa-coloma-contra-el-cuer-lhospitalense","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/ocasio-dor-per-lalevi-c-de-la-f-e-grama-a-santa-coloma-contra-el-cuer-lhospitalense\/","title":{"rendered":"Ocasi\u00f3 d&#8217;or per l&#8217;Alev\u00ed C de la F.E. Grama a Santa Coloma contra el cuer, l&#8217;Hospitalense"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A punt de remuntar a casa de la<strong> Zona Franca<\/strong> (cinqu\u00e8 classificat) on finalment es va perdre per l&#8217;ajustat 7-6, l<strong>&#8216;Alev\u00ed C de la Fundaci\u00f3 Grama<\/strong> te l&#8217;ocasi\u00f3 d&#8217;or a l&#8217;enfrontament contra el cuer, <strong>l&#8217;Hospitalense<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aquest partit que els de la <strong>Fundaci\u00f3 Grama<\/strong> dirigits per <strong>Jos\u00e9 Mar\u00eda Tiz\u00f3n<\/strong>, dotzens a la classificaci\u00f3 amb 13 punts de quatre vict\u00f2ries i un empat, ser\u00e0 una clara oportunitat de tornar a agafar bons resultats.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A m\u00e9s aprofitarem que es jugar\u00e0 al <strong>Nou Municipal de Santa Coloma<\/strong> el pr\u00f2xim <strong>diumenge 16 de febrer des de les 14 de la tarda<\/strong> per animar als socis i aficionats al futbol que recolzin als joves jugadors de la <strong>Fundaci\u00f3 Esportiva Grama.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Al\u00e9 Grama!!!<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A punto de remontar en casa de la Zona Franca (quinto clasificado) donde finalmente se perdi\u00f3 por el ajustado 7-6, el Alev\u00edn C de la Fundaci\u00f3n Grama tiene la ocasi\u00f3n de oro en el enfrentamiento contra el colista, el Hospitalense.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Este partido que los de la Fundaci\u00f3n Grama dirigidos por Jos\u00e9 Mar\u00eda Tiz\u00f3n, duod\u00e9cimos en la clasificaci\u00f3n con 13 puntos de cuatro victorias y un empate, ser\u00e1 una clara oportunidad de volver a coger buenos resultados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Adem\u00e1s aprovecharemos que se jugar\u00e1 en el Nou Municipal de Santa Coloma el pr\u00f3ximo domingo 16 de febrero desde las 14 de la tarde para animar a los socios y aficionados al f\u00fatbol que apoyen a los j\u00f3venes jugadores de la Fundaci\u00f3 Esportiva Grama.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A punt de remuntar a casa de la Zona Franca (cinqu\u00e8 classificat) on finalment es va perdre per l&#8217;ajustat 7-6, l&#8216;Alev\u00ed C de la Fundaci\u00f3 Grama te l&#8217;ocasi\u00f3 d&#8217;or a l&#8217;enfrontament contra el cuer, l&#8217;Hospitalense. Aquest partit que els de la Fundaci\u00f3 Grama dirigits per Jos\u00e9 Mar\u00eda Tiz\u00f3n, dotzens a la classificaci\u00f3 amb 13 punts [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,4],"tags":[19,24,20,155,21,474],"class_list":["post-2051","post","type-post","status-publish","format-standard","hentry","category-alevins","category-base-inclusiu","tag-feg","tag-fundacio-esportiva-grama","tag-fundacio-grama","tag-hospitalense","tag-santa-coloma","tag-zona-franca"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=2051"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2051\/revisions"}],"predecessor-version":[{"id":2054,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/2051\/revisions\/2054"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=2051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=2051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=2051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}