{"id":17902,"date":"2016-10-23T17:59:46","date_gmt":"2016-10-23T16:59:46","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=17902"},"modified":"2016-10-23T17:59:46","modified_gmt":"2016-10-23T16:59:46","slug":"linfantil-c-va-guanyar-a-badalona","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/linfantil-c-va-guanyar-a-badalona\/","title":{"rendered":"L&#8217;Infantil C va guanyar a Badalona"},"content":{"rendered":"<p>Al Municipal de Pomar l&#8217;Infantil C va sumar una important vict\u00f2ria per 1-5 davant la Unificaci\u00f3n Llefi\u00e0.<\/p>\n<p>La Fundaci\u00f3 va fer una gran primera meitat, dominant completament per\u00f2 amb falta de ritme a la circulaci\u00f3 de la pilota. Els locals no van tenir cap oportunitat en una primera meitat que va acabar 0-2 amb dos gols de Dennis Josep. Despr\u00e9s del descans la Grama va seguir millor sobre la gespa, posant un ritme de joc molt alt.<\/p>\n<p>Ian i \u00cdker van augmentar l&#8217;avantatge a 0-4. Pocs errors en defensa en una segona meitat en qu\u00e8 la Llefi\u00e0 va tenir alguna oportunitat de marcar, i en una d&#8217;elles va arribar el gol. El gol local no va significar res, la Fundaci\u00f3 va seguir treballant molt b\u00e9 i abans del final Dennis Josep marcava el definitiu 1-5 i el seu hat-trick.<\/p>\n<p>[divider]<\/p>\n<p>En el Municipal de Pomar el Infantil C sum\u00f3 una importante victoria por 1-5 ante la Unificaci\u00f3n Llefi\u00e0.<\/p>\n<p>La Fundaci\u00f3 hizo una gran primera mitad, dominando completamente pero con falta de ritmo en la circulaci\u00f3n de la pelota. Los locales no tuvieron ninguna oportunidad en una primera mitad que acab\u00f3 0-2 con dos goles de Dennis Josep. Tras el descanso la Grama sigui\u00f3 mejor sobre el c\u00e9sped, poniendo un ritmo de juego muy alto.<\/p>\n<p>Ian e \u00cdker aumentaron la ventaja a 0-4. Pocos fallos en defensa en una segunda mitad en la que la Llefi\u00e0 tuvo alguna oportunidad de marcar, y en una de ellas lleg\u00f3 el gol. El gol local no signific\u00f3 nada, la Fundaci\u00f3 sigui\u00f3 trabajando muy bien y antes del final Dennis Josep marcaba el definitivo 1-5 y su hat-trick.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al Municipal de Pomar l&#8217;Infantil C va sumar una important vict\u00f2ria per 1-5 davant la Unificaci\u00f3n Llefi\u00e0. La Fundaci\u00f3 va fer una gran primera meitat, dominant completament per\u00f2 amb falta de ritme a la circulaci\u00f3 de la pilota. Els locals no van tenir cap oportunitat en una primera meitat que va acabar 0-2 amb dos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":6232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"class_list":["post-17902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-infantils"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=17902"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17902\/revisions"}],"predecessor-version":[{"id":17903,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17902\/revisions\/17903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/6232"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=17902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=17902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=17902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}