{"id":17746,"date":"2016-10-16T19:49:00","date_gmt":"2016-10-16T18:49:00","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=17746"},"modified":"2016-10-16T19:49:00","modified_gmt":"2016-10-16T18:49:00","slug":"lalevi-g-va-caure-a-les-oliveres-2","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/lalevi-g-va-caure-a-les-oliveres-2\/","title":{"rendered":"L&#8217;Alev\u00ed G va caure a Les Oliveres"},"content":{"rendered":"<p>Dissabte a Les Oliveres l&#8217;Alev\u00ed G va encaixar una dolorosa derrota davant el FC Zona Franca. Despr\u00e9s de posar-se 3-0 acabaria perdent 3-5.<\/p>\n<p>Mal gust de boca, els colomencs van fer una brillant primera meitat per\u00f2 van sucumbir amb una mala segona part. Uriel Garc\u00eda en dues ocasions i Kilian van deixar un marcador de 3-0 al descans. Tot feia indicar que els tres punts se&#8217;ls portarien els colomencs per\u00f2 el gui\u00f3 del partit va canviar. Al tercer quart els jugadors del Zona Franca van aconseguir empatar el partit i en l&#8217;\u00faltim quart van remuntar.<\/p>\n<p>[divider]<\/p>\n<p>El s\u00e1bado en Les Oliveres el Alev\u00edn G encaj\u00f3 una dolorosa derrota ante el FC Zona Franca. Despu\u00e9s de ponerse 3-0 acabar\u00eda perdiendo 3-5.<\/p>\n<p>Mal sabor de boca, los colomenses hicieron una brillante primera mitad pero sucumbieron con una mala segunda parte. Uriel Garc\u00eda en dos ocasiones y Kilian dejaron un marcador de 3-0 al descanso. Todo hac\u00eda indicar que los tres puntos se los llevar\u00edan los colomenses pero el gui\u00f3n del partido cambi\u00f3. En el tercer cuarto los jugadores del Zona Franca consiguieron empatar el partido y en el \u00faltimo cuarto remontaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dissabte a Les Oliveres l&#8217;Alev\u00ed G va encaixar una dolorosa derrota davant el FC Zona Franca. Despr\u00e9s de posar-se 3-0 acabaria perdent 3-5. Mal gust de boca, els colomencs van fer una brillant primera meitat per\u00f2 van sucumbir amb una mala segona part. Uriel Garc\u00eda en dues ocasions i Kilian van deixar un marcador de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,4],"tags":[],"class_list":["post-17746","post","type-post","status-publish","format-standard","hentry","category-alevins","category-base-inclusiu"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=17746"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17746\/revisions"}],"predecessor-version":[{"id":17747,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17746\/revisions\/17747"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=17746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=17746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=17746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}