{"id":17097,"date":"2016-06-26T10:03:09","date_gmt":"2016-06-26T09:03:09","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=17097"},"modified":"2016-06-27T10:00:21","modified_gmt":"2016-06-27T09:00:21","slug":"bon-paper-dels-nostres-equips-al-fit","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/bon-paper-dels-nostres-equips-al-fit\/","title":{"rendered":"Bon paper dels nostres equips al FIT"},"content":{"rendered":"<p>La tarda del dijous 23 de juny donava comen\u00e7ament el <strong>Footvia International Tournament<\/strong>, un gran torneig organitzat en diferents instal\u00b7lacions i on la <strong>Fundaci\u00f3 Esportiva Grama<\/strong> estava representada per tres equips. Els primers a saltar al terreny de joc van ser el <strong>Cadet A<\/strong> de <strong>Christian Rueda<\/strong> i el <strong>Benjam\u00ed<\/strong> de <strong>Marcos D\u00edaz<\/strong>, divendres va ser el torn de l&#8217;<strong>Infantil-Alev\u00ed Femen\u00ed<\/strong> de <strong>Rub\u00e9n David Hern\u00e1ndez<\/strong> i <strong>Jordi P\u00e9rez<\/strong>.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGORIA SUB-16<\/strong><\/span><\/p>\n<p>Gran debut dijous pel Cadet A de la Grama. Sense fer un gran partit van guanyar amb facilitat per <strong>2-0<\/strong> a <strong>La Planada Sabadell<\/strong>, van dominar en tot moment amb un ritme fluixet per\u00f2 sent molt superiors al rival. El resultat va poder haver estat molt m\u00e9s gran.<\/p>\n<p>Divendres doble treball, primer empat davant el <strong>Extravagantes<\/strong>, un rival molt complicat i dur. La Grama sempre va anar per davant en el marcador per\u00f2 desgraciadament en l&#8217;\u00faltim segon va arribar el <strong>2-2<\/strong>. Amb menys descans que el seu rival els tocava enfrontar-se al <strong>Intensos FC<\/strong> a que van guanyar <strong>3-1<\/strong>. Molt bon partit, tenint la pilota i competint molt b\u00e9.<\/p>\n<p>Al dia seg\u00fcent de nou al Camp Municipal de Nou Barris es van jugar la primera pla\u00e7a contra el <strong>Real Murcia<\/strong>. L&#8217;<strong>1-1<\/strong> donava el primer lloc del grup als colomencs per jugar els quarts de final davant la <strong>UE Sant Andreu<\/strong>.\u00a0Els colomencs van arribar al partit cansats, a penes van poder arribar a l&#8217;altre \u00e0rea, els barcelonins van ser superiors fins i tot quan van jugar amb un home menys, finalment derrota per <strong>0-2<\/strong>.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGORIA SUB-14 FEMENINA<\/strong><\/span><\/p>\n<p>Al camp del PereGol van jugar les nostres noies, un lloc molt petit perqu\u00e8 puguin brillar les jugadores al Futbol 7. El <strong>Valencia CF<\/strong> amb molt f\u00edsic es va dur el primer partit guanyant a les noies de <strong>Rub\u00e9n David Hern\u00e1ndez<\/strong> i <strong>Jordi P\u00e9rez<\/strong> per un resultat de <strong>1-5<\/strong>. La m\u00e0gia de les nostres &#8216;guerreres&#8217; es va poder veure davant el <strong>Footvia<\/strong> al qual van guanyar <strong>2-4<\/strong> en un partit amb un resultat que va poder haver estat m\u00e9s gran a favor de la<strong> Grama<\/strong>.<\/p>\n<p>Les opcions de passar a semifinals passaven amb guanyar dissabte com a m\u00ednim un partit. Van lluitar i van plantar cara a un dels equips favorits, el <strong>Mercantil<\/strong> que va guanyar <strong>0-3<\/strong> gr\u00e0cies en part a dos xuts llunyans. Dia sense sort de cara a gol, amb ocasions desaprofitades i algun pal desviant el gol, i davant el <strong>CD Arrabal-Calaf de Gramenet<\/strong> queien eliminades en perdre <strong>2-0<\/strong> resultat immerescut veient el gran partit que les nostres noies van fer.<\/p>\n<p>El torneig el van tancar a la tarda enfrontant-se al<strong> RCD Espanyol<\/strong>, derrota<strong> 0-5<\/strong> en un \u00faltim esfor\u00e7 de les nostres noies que arribaven al partit molt cansades i tocades ja que eren nom\u00e9s 7 jugadores per les 3 baixes que hi va haver.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGORIA 2006<\/strong><\/span><\/p>\n<p>El debut dels nostres benjamins a la Vall d&#8217;Hebron-Teixonera acabaria en derrota per <strong>2-0<\/strong> davant el poder\u00f3s <strong>Valencia CF<\/strong>. Divendres tampoc hi va haver sort en caure<strong> 5-1<\/strong> davant l&#8217;<strong>Uni\u00f3<\/strong>\u00a0<strong>Jabac i Terrassa<\/strong>\u00a0i <strong>0-1<\/strong> davant el <strong>Can Buxeres<\/strong>. Al darrer partit de la fase de grups la Grama i el <strong>Don Bosco<\/strong> s&#8217;enfrontaven per aconseguir passar a vuitens, la golejada <em><strong>(8-0)<\/strong> <\/em>dels colomencs li donava el bitllet a la seg\u00fcent ronda.<\/p>\n<p>El mateix dissabte, ja a la tarda, es van enfrontar al <strong>Grama Sports\u00a0<\/strong>amb qui van perdre <strong>4-2<\/strong> quedant aix\u00ed eliminats.\u00a0Els colomencs es van deixar la pell durant tot el torneig.<\/p>\n<figure id=\"attachment_17100\" aria-describedby=\"caption-attachment-17100\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/06\/cadA260616.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-17100\" alt=\"cadA260616\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/06\/cadA260616.jpg\" width=\"560\" height=\"391\" \/><\/a><figcaption id=\"caption-attachment-17100\" class=\"wp-caption-text\"><strong>Foto del Cadete de Christian Rueda en el Torneo.<\/strong><\/figcaption><\/figure>\n<p>La tarde del jueves 23 de junio daba comienzo el\u00a0<strong>Footvia International Tournament<\/strong>, un gran torneo organizado en diferentes instalaciones y donde la <strong>Fundaci\u00f3 Esportiva Grama<\/strong> estaba representada por tres equipos. Los primeros en saltar al terreno de juego fueron el <strong>Cadete A<\/strong> de <strong>Christian Rueda<\/strong> y el <strong>Benjam\u00edn<\/strong> de <strong>Marcos D\u00edaz<\/strong>, el viernes fue el turno del<strong> Infantil-Alev\u00edn Femenino<\/strong> de <strong>Rub\u00e9n David Hern\u00e1ndez<\/strong> y <strong>Jordi P\u00e9rez<\/strong>.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGOR\u00cdA SUB-16<\/strong><\/span><\/p>\n<p>Gran debut el jueves para el Cadete A de la Grama. Sin hacer un gran partido ganaron con facilidad por <strong>2-0<\/strong> a <strong>La Planada Sabadell<\/strong>, dominaron en todo momento con un ritmo flojito pero siendo muy superiores al rival. El resultado pudo haber sido mucho mayor.<\/p>\n<p>El viernes doble trabajo, primero empate ante el <strong>Extravagantes<\/strong>, un rival muy complicado y duro. La <strong>Grama<\/strong> siempre fue por delante en el marcador pero desgraciadamente en el \u00faltimo segundo lleg\u00f3 el <strong>2-2<\/strong>. Con menos descanso que su rival les tocaba enfrentarse al <strong>Intensos FC<\/strong> al que ganaron <strong>3-1<\/strong>. Muy buen partido, teniendo la pelota y compitiendo muy bien.<\/p>\n<p>Al d\u00eda siguiente de nuevo en el\u00a0Camp Municipal de Nou Barris se jugaron la primera plaza contra el<strong> Real Murcia<\/strong>. El <strong>1-1<\/strong> daba el primer puesto del grupo a los colomenses para jugar los cuartos de final ante la<strong> UE Sant Andreu<\/strong>.\u00a0Los colomenses llegaron al partido cansados, a penas pudieron llegar al otro \u00e1rea, los barcelonenses fueron superiores incluso cuando jugaron con uno menos, finalmente derrota por\u00a0<strong>0-2<\/strong>.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGOR\u00cdA SUB-14 FEMENINA<\/strong><\/span><\/p>\n<p>En el campo del PereGol jugaron nuestras chicas, un lugar muy peque\u00f1o para que puedan brillar las jugadoras en F\u00fatbol 7. El <strong>Valencia CF<\/strong> con mucho f\u00edsico se llevo el primer partido ganando a las chicas de\u00a0<strong>Rub\u00e9n David Hern\u00e1ndez<\/strong> y <strong>Jordi P\u00e9rez<\/strong> por un resultado de <strong>1-5<\/strong>. La magia de nuestras &#8216;guerreras&#8217; se pudo ver ante el <strong>Footvia<\/strong> al que ganaron<strong> 2-4<\/strong> en un partido con un resultado que pudo haber sido mayor a favor de la Grama.<\/p>\n<p>Las opciones de pasar a semifinales pasaban con ganar el s\u00e1bado al menos un partido. Lucharon y plantaron cara a uno de los equipos favoritos, el <strong>Mercantil<\/strong> que gan\u00f3 <strong>0-3<\/strong> gracias en parte a dos disparos lejanos. D\u00eda sin suerte de cara a gol, con ocasiones desperdiciadas y alg\u00fan palo desviando el gol, y ante el <strong>CD Arrabal-Calaf de Gramene<\/strong>t ca\u00edan eliminadas al perder<strong> 2-0<\/strong> resultado inmerecido viendo el gran partido que nuestras chicas hicieron.<\/p>\n<p>El torneo lo cerraron por la tarde enfrent\u00e1ndose al <strong>RCD Espanyol<\/strong>, derrota<strong> 0-5<\/strong> en un \u00faltimo esfuerzo de nuestras chicas que llegaban al partido muy cansadas y tocadas ya que eran solamente 7 jugadoras por las 3 bajas que hubo.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>CATEGOR\u00cdA 2006<\/strong><\/span><\/p>\n<p>El debut de nuestros benjamines en el\u00a0Vall d&#8217;Hebron-Teixonera acabar\u00eda en derrota por<strong> 2-0<\/strong> ante el poderoso<strong> Valencia CF<\/strong>. El viernes tampoco hubo suerte al caer<strong> 5-1<\/strong> ante el <strong>Uni\u00f3<\/strong>\u00a0<strong>Jabac i Terrassa<\/strong> y<strong> 0-1<\/strong> ante el <strong>Can Buxeres<\/strong>. En el \u00faltimo partido de la fase de grupos la Grama y el <strong>Don Bosco<\/strong> se enfrentaban para conseguir pasar a octavos, la goleada <strong><em>(8-0)<\/em> <\/strong>de los colomenses le daba el billete a la siguiente ronda.<\/p>\n<p>El mismo s\u00e1bado, ya por la tarde, se enfrentaron al <strong>Grama Sports\u00a0<\/strong>con quien perdieron <strong>4-2<\/strong> quedando as\u00ed eliminados. Los colomenses se dejaron la piel durante todo el torneo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tarda del dijous 23 de juny donava comen\u00e7ament el Footvia International Tournament, un gran torneig organitzat en diferents instal\u00b7lacions i on la Fundaci\u00f3 Esportiva Grama estava representada per tres equips. Els primers a saltar al terreny de joc van ser el Cadet A de Christian Rueda i el Benjam\u00ed de Marcos D\u00edaz, divendres va [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[24],"class_list":["post-17097","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-fundacio-esportiva-grama"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=17097"}],"version-history":[{"count":4,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17097\/revisions"}],"predecessor-version":[{"id":17106,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/17097\/revisions\/17106"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=17097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=17097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=17097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}