{"id":15002,"date":"2016-02-15T10:26:14","date_gmt":"2016-02-15T09:26:14","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=15002"},"modified":"2016-02-15T10:26:14","modified_gmt":"2016-02-15T09:26:14","slug":"el-cadet-b-no-va-poder-amb-leuropa","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-cadet-b-no-va-poder-amb-leuropa\/","title":{"rendered":"El Cadet B no va poder amb l&#8217;Europa"},"content":{"rendered":"<p>Dissabte al Nou Municipal l&#8217;equip d&#8217;Oscar P\u00e9rez no va poder derrotar al CE Europa C.<\/p>\n<p>Molt bons primers deu minuts de domini local, aconseguint Eric el 1-0 al minut 12. El domini del Cadet B va seguir fins al minut 20 quan el bon joc quedava truncat per un penal dubt\u00f3s, l&#8217;Europa aconseguia empatar i tan sols tres minuts despr\u00e9s li donava la volta al marcador.<\/p>\n<p>Els colomencs van buscar l&#8217;empat abans del descans per\u00f2 no ho van aconseguir. Despr\u00e9s del pas per vestuaris la segona meitat comen\u00e7ava de la pitjor manera, als dos minuts de falta els visitants marcaven el 1-3, un resultat volumin\u00f3s veient les ocasions d&#8217;un i altre equip. La Fundaci\u00f3 buscaria retallar la difer\u00e8ncia de gols per\u00f2 no ho van aconseguir fins a l&#8217;\u00faltim minut de joc quan \u00c0ngel marcava el definitiu 2-3.<\/p>\n<p><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2013\/12\/DSC1817.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14879\" alt=\"Cadet B 1516\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2013\/12\/DSC1817-1024x664.jpg\" width=\"618\" height=\"400\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2013\/12\/DSC1817-1024x664.jpg 1024w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2013\/12\/DSC1817-300x194.jpg 300w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/a><\/p>\n<p>El s\u00e1bado en el Nou Municipal el equipo de Oscar P\u00e9rez no pudo derrotar al CE Europa C.<\/p>\n<p>Muy buenos primeros diez minutos de dominio local, consiguiendo Eric el 1-0 en el minuto 12. El dominio del Cadete B sigui\u00f3 hasta el minuto 20 cuando el buen juego quedaba truncado por un penalti dudoso, el Europa consegu\u00eda empatar y tan s\u00f3lo tres minutos despu\u00e9s le daba la vuelta al marcador.<\/p>\n<p>Los colomenses buscaron el empate antes del descanso pero no lo consiguieron. Tras el paso por vestuarios la segunda mitad empezaba de la peor manera, a los dos minutos de falta los visitantes marcaban el 1-3, un resultado abultado viendo las ocasiones de uno y otro equipo. La Fundaci\u00f3 buscar\u00eda recortar la diferencia de goles pero no lo consiguieron hasta el \u00faltimo minuto de juego cuando \u00c1ngel marcaba el definitivo 2-3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dissabte al Nou Municipal l&#8217;equip d&#8217;Oscar P\u00e9rez no va poder derrotar al CE Europa C. Molt bons primers deu minuts de domini local, aconseguint Eric el 1-0 al minut 12. El domini del Cadet B va seguir fins al minut 20 quan el bon joc quedava truncat per un penal dubt\u00f3s, l&#8217;Europa aconseguia empatar i [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[701,24,55],"class_list":["post-15002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-cadets","tag-ce-europa","tag-fundacio-esportiva-grama","tag-nou-municipal-de-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/15002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=15002"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/15002\/revisions"}],"predecessor-version":[{"id":15003,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/15002\/revisions\/15003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/14879"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=15002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=15002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=15002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}