{"id":14690,"date":"2016-01-28T14:36:17","date_gmt":"2016-01-28T13:36:17","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=14690"},"modified":"2016-01-29T12:45:18","modified_gmt":"2016-01-29T11:45:18","slug":"diumenge-al-nou-municipal-juguen-els-veterans","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/diumenge-al-nou-municipal-juguen-els-veterans\/","title":{"rendered":"Diumenge al Nou Municipal juguen els Veterans"},"content":{"rendered":"<p>Despr\u00e9s de golejar a Badia del Vall\u00e8s i aprofitar la punxada del segon classificat per tenir ara 3 punts d&#8217;avantatge l&#8217;equip vol seguir la bona l\u00ednia guanyant fora de casa.<\/p>\n<p style=\"text-align: center;\"><strong>Diumenge a les 08 hores juguen al Nou Municipal de Santa Coloma davant el Ripollet.<\/strong><\/p>\n<p>Sis\u00e8 classificat de la lliga, ve amb for\u00e7a. Sens dubte ser\u00e0 un partit complicat davant un gran rival. Emocionant i atractiu.<\/p>\n<p><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2015\/10\/veterans1516.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" alt=\"veterans1516\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2015\/10\/veterans1516.jpg\" width=\"710\" height=\"362\" \/><\/a><\/p>\n<p>Despu\u00e9s de golear en\u00a0Badia del Vall\u00e8s y aprovechar el pinchazo del segundo clasificado para tener ahora 3 puntos de ventaja el equipo quiere seguir la buena l\u00ednea ganando fuera de casa.<\/p>\n<p style=\"text-align: center;\"><strong>El domingo a las 08 horas juegan en el Nou Municipal de Santa Coloma ante el Ripollet.<\/strong><\/p>\n<p>Sexto clasificado de la liga, viene con fuerza. Sin duda ser\u00e1 un partido complicado ante un gran rival. Emocionante y atractivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e9s de golejar a Badia del Vall\u00e8s i aprofitar la punxada del segon classificat per tenir ara 3 punts d&#8217;avantatge l&#8217;equip vol seguir la bona l\u00ednia guanyant fora de casa. Diumenge a les 08 hores juguen al Nou Municipal de Santa Coloma davant el Ripollet. Sis\u00e8 classificat de la lliga, ve amb for\u00e7a. Sens dubte [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":13059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,751],"tags":[24,612],"class_list":["post-14690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-base-inclusiu","category-veterans","tag-fundacio-esportiva-grama","tag-veterans-grama"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=14690"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14690\/revisions"}],"predecessor-version":[{"id":14691,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14690\/revisions\/14691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/13059"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=14690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=14690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=14690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}