{"id":14655,"date":"2016-01-28T22:59:32","date_gmt":"2016-01-28T21:59:32","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=14655"},"modified":"2016-02-02T18:58:16","modified_gmt":"2016-02-02T17:58:16","slug":"benvingut-a-la-fundacio-angel-wu","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/benvingut-a-la-fundacio-angel-wu\/","title":{"rendered":"A. Wu refor\u00e7 oriental per la davantera del Cadet A"},"content":{"rendered":"<figure id=\"attachment_14668\" aria-describedby=\"caption-attachment-14668\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/wang2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14668 \" alt=\"D'esquerra a dreta: Daniel Borrallo (directiu), Antonio Morales (president), \u00c1ngel Wu i Manolo Garc\u00eda (responsable de l'\u00e0rea esportiva).\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/wang2.jpg\" width=\"560\" height=\"420\" \/><\/a><figcaption id=\"caption-attachment-14668\" class=\"wp-caption-text\">D&#8217;esquerra a dreta: <strong>Daniel Borrallo (directiu), Antonio Morales (president), \u00c1ngel Wu i Manolo Garc\u00eda (responsable de l&#8217;\u00e0rea esportiva).<\/strong><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>\u00c1ngel Wu<\/strong> <em>(08\/05\/2000, Vit\u00f2ria)<\/em> \u00e9s el nou refor\u00e7 del Cadet A. El jove jugador t\u00e9 15 anys i els seus pares s\u00f3n de la ciutat de <strong>Qingtian <em>(Xina)<\/em><\/strong>. La seva posici\u00f3 ideal \u00e9s extrem per\u00f2 pot tamb\u00e9 actuar com a punta. Fa dos anys jugava en la PB Cinc Copes i la temporada passada al At.Piferrer, mesos despr\u00e9s el van enviar a la tecnificaci\u00f3 del RCD Espanyol i ells li van aconsellar que vingu\u00e9s a la Grama perqu\u00e8 era un bon equip per estar i aprendre.<\/p>\n<p style=\"text-align: justify;\">Un seguidor del R.Madrid i molt fan de Cristiano Ronaldo. El noi se sent orgull\u00f3s del vincle que han format <strong>LAMA Football Academy<\/strong> i la<strong> FE Grama<\/strong> ja que tant ell com altres jugadors del seu pa\u00eds podran venir a Santa Coloma a provar i sobretot entrenar i aprendre del gran nivell futbol\u00edstic espanyol.<\/p>\n<blockquote><p><strong>\u00c1ngel:<\/strong> \u00abM&#8217;agrada molt les bones relacions que t\u00e9 la Fundaci\u00f3 amb LAMA. Veig molt pocs paisans meus a Espanya jugant i aquesta relaci\u00f3 \u00e9s bonica perqu\u00e8 obre portes. Als xinesos els agrada el futbol, \u200b\u200bper\u00f2 una altra cosa \u00e9s que no tinguis sort perqu\u00e8 en aquest esport a m\u00e9s de ser bo necessites tenir una mica de sort i sobretot necessites treballar molt.\u00bb<\/p><\/blockquote>\n<h1 style=\"text-align: center;\"><strong>\u4f60\u597d\uff0c\u6211\u9f13\u52f5\u4f60\u4f86\u6253GRAMA<\/strong><\/h1>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/WANG1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-14667\" alt=\"WANG1\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/WANG1.jpg\" width=\"640\" height=\"480\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/WANG1.jpg 800w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/WANG1-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/wang3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-14669\" alt=\"wang3\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/wang3.jpg\" width=\"618\" height=\"463\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>\u00c1ngel Wu<\/strong><em> (08\/05\/2000, Vitoria)<\/em> es el nuevo refuerzo del Cadete A. El joven jugador tiene 15 a\u00f1os y sus padres son de la ciudad de\u00a0<strong>Qingtian <em>(China)<\/em><\/strong>. Su posici\u00f3n ideal es extremo pero puede tambi\u00e9n actuar como punta. Hace dos a\u00f1os jugaba en la PB Cinc Copes y la temporada pasada en el At.Piferrer, meses despu\u00e9s le enviaron a la tecnificaci\u00f3n del RCD Espanyol y ellos le aconsejaron que viniera a la Grama porqu\u00e9 era un buen equipo para estar y aprender.<\/p>\n<p style=\"text-align: justify;\">Un seguidor del R.Madrid y muy fan de Cristiano Ronaldo. El chico se siente orgulloso del vinculo que han formado <strong>LAMA Football Academy<\/strong> y la <strong>FE Grama<\/strong> ya que tanto \u00e9l como otros jugadores de su pa\u00eds podr\u00e1n venir a Santa Coloma a probar y sobretodo entrenar y aprender del gran nivel futbol\u00edstico espa\u00f1ol.<\/p>\n<blockquote>\n<p style=\"text-align: left;\"><strong>\u00c1ngel:<\/strong> \u00abMe gusta mucho las buenas relaciones que tiene la Fundaci\u00f3 con LAMA. Veo muy pocos paisanos m\u00edos en Espa\u00f1a jugando y esta relaci\u00f3n es bonita porqu\u00e9 abre puertas. A los chinos les gusta el f\u00fatbol, pero otra cosa es que no tengas suerte porqu\u00e9 en este deporte adem\u00e1s de ser bueno necesitas tener algo de suerte y sobretodo necesitas trabajar mucho.\u00bb<\/p>\n<\/blockquote>\n<h1 style=\"text-align: center;\"><strong>\u4f60\u597d\uff0c\u6211\u9f13\u52f5\u4f60\u4f86\u6253GRAMA<\/strong><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1ngel Wu (08\/05\/2000, Vit\u00f2ria) \u00e9s el nou refor\u00e7 del Cadet A. El jove jugador t\u00e9 15 anys i els seus pares s\u00f3n de la ciutat de Qingtian (Xina). La seva posici\u00f3 ideal \u00e9s extrem per\u00f2 pot tamb\u00e9 actuar com a punta. Fa dos anys jugava en la PB Cinc Copes i la temporada passada al [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1009],"class_list":["post-14655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-academia-lama"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=14655"}],"version-history":[{"count":5,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14655\/revisions"}],"predecessor-version":[{"id":14696,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14655\/revisions\/14696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/14667"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=14655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=14655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=14655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}