{"id":1464,"date":"2014-01-19T20:05:42","date_gmt":"2014-01-19T20:05:42","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=1464"},"modified":"2014-01-19T20:05:42","modified_gmt":"2014-01-19T20:05:42","slug":"linfantil-b-de-la-f-e-grama-es-col-loca-quart-pel-triomf-davant-el-carmelo-al-nou-municipal-de-santa-coloma","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/linfantil-b-de-la-f-e-grama-es-col-loca-quart-pel-triomf-davant-el-carmelo-al-nou-municipal-de-santa-coloma\/","title":{"rendered":"L&#8217;Infantil B de la F.E.Grama es col.loca quart pel triomf davant el Carmelo al Nou Municipal de Santa Coloma"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-L\u2019<strong>Infantil B de la Fundaci\u00f3 Esportiva Grama<\/strong>\u00a0segueix remuntant posicions i demostrant que est\u00e0 a la part de dalt (amb una jornada menys) a nom\u00e8s 7 punts del l\u00edder, <strong>Escola Sarri\u00e0<\/strong>, per haver guanyat al <strong>Carmelo<\/strong> per 7-0 al <strong>Nou Municipal de Santa Coloma.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Amb aquest triomf s\u00f3n ja 9 vict\u00f2ries de 12 jornades gr\u00e0cies aquest cop ales gols de<strong> Connor Dempsey<\/strong>, al doblet d&#8217;<strong>\u00c0lex Castillo i el de Wanderson Souza m\u00e9s el gol de Ra\u00fal Castillo.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la pr\u00f2xima jornada, la 14 per\u00f2 la 12 per tots dos contendients, ser\u00e0 en un derbi colomenc al <strong>Municipal Can Zam 2<\/strong> contra el Imperio, a un punt i un lloc per damunt dels\u00a0dirigits per\u00a0<strong>Rafa Avil\u00e9s i Ramon Dom\u00ednguez<\/strong>, el dissabte 25 de gener a les 14:15 hores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-L&#8217;Infantil B de la Fundaci\u00f3n Deportiva Grama sigue demostrando que est\u00e1 en la parte de arriba (con una jornada menos) a s\u00f3lo 7 puntos del l\u00edder, Escuela Sarri\u00e0, por haber ganado a Carmelo por 7-0 en el Nou Municipal de Santa Coloma .<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con este triunfo son ya 9 victorias de 12 jornadas gracias esta vez alas goles de Connor Dempsey, el doblete de Alex Castillo y el de Wanderson Souza m\u00e1s el gol de Ra\u00fal Castillo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la pr\u00f3xima jornada, la 14 pero la 12 para ambos contendientes, ser\u00e1 en un derby colomense el Municipal Can Zam 2 contra el Imperio, a un punto y un lugar por encima de los dirigidos por Rafa Avil\u00e9s y Ram\u00f3n Dom\u00ednguez, el s\u00e1bado 25 de enero a las 14:15 horas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-L\u2019Infantil B de la Fundaci\u00f3 Esportiva Grama\u00a0segueix remuntant posicions i demostrant que est\u00e0 a la part de dalt (amb una jornada menys) a nom\u00e8s 7 punts del l\u00edder, Escola Sarri\u00e0, per haver guanyat al Carmelo per 7-0 al Nou Municipal de Santa Coloma. Amb aquest triomf s\u00f3n ja 9 vict\u00f2ries de 12 jornades gr\u00e0cies aquest [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[251,302,24,303,27,55,21,83],"class_list":["post-1464","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-infantils","tag-carmelo","tag-escola-sarria","tag-fundacio-esportiva-grama","tag-municipal-can-zam-2","tag-nou-municipal","tag-nou-municipal-de-santa-coloma","tag-santa-coloma","tag-sarria"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1466,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1466"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}