{"id":1461,"date":"2014-01-19T19:47:35","date_gmt":"2014-01-19T19:47:35","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=1461"},"modified":"2014-01-19T19:47:35","modified_gmt":"2014-01-19T19:47:35","slug":"linfantil-a-de-la-f-e-grama-per-davant-el-mercantil-cinque-classificat","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/linfantil-a-de-la-f-e-grama-per-davant-el-mercantil-cinque-classificat\/","title":{"rendered":"L\u2019Infantil A de la F.E.Grama perd davant el Mercantil, cinqu\u00e8 classificat"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">&#8211;<strong>L\u2019Infantil A<\/strong>\u00a0de la<strong>\u00a0Fundaci\u00f3 Grama<\/strong>\u00a0ha caigut al\u00a0<strong>Nou Municipal de Santa Coloma<\/strong>\u00a0el dissabte 18 de gener a la jornada 13 davant el\u00a0<strong>Mercantil<\/strong>, cinqu\u00e8 classificat, per 0-2.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ara fem una crida per donar suport a tota l\u2019afici\u00f3 de la Fundaci\u00f3 Grama al<strong>\u00a0<strong>Nou Municipal de Santa Coloma de Gramenet<\/strong><\/strong>\u00a0el pr\u00f2xim cap de setmana\u00a0rep al <strong>Badalona<\/strong>, vuit\u00e8 classificat amb 15 punts a la jornada 14 el diumenge 26 de gener des de les 15:30 hores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vinga \u00e0nims a l&#8217;equip de la Fundaci\u00f3 Esportiva Grama i acudiu al nostres estadi municipal per animar tots els joves jugadors.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-L&#8217;Infantil A de la Fundaci\u00f3n Grama ha ca\u00eddo en el Nou Municipal de Santa Coloma el s\u00e1bado 18 de enero en la jornada 13 ante el Mercantil, quinto clasificado, por 0-2.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Ahora hacemos un llamamiento para apoyar a toda la afici\u00f3n de la Fundaci\u00f3n Grama en el Nou Municipal de Santa Coloma el pr\u00f3ximo fin de semana recibe al Badalona, octavo clasificado con 15 puntos en la jornada 14 el domingo 26 de enero desde las 15:30 horas. <\/span><br \/>\n<span style=\"color: #000000;\">Vamos \u00e1nimos al equipo de la Fundaci\u00f3nEsportiva Grama y acudir a nuestros estadio municipal para animar a todos los j\u00f3venes jugadores.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;L\u2019Infantil A\u00a0de la\u00a0Fundaci\u00f3 Grama\u00a0ha caigut al\u00a0Nou Municipal de Santa Coloma\u00a0el dissabte 18 de gener a la jornada 13 davant el\u00a0Mercantil, cinqu\u00e8 classificat, per 0-2. Ara fem una crida per donar suport a tota l\u2019afici\u00f3 de la Fundaci\u00f3 Grama al\u00a0Nou Municipal de Santa Coloma de Gramenet\u00a0el pr\u00f2xim cap de setmana\u00a0rep al Badalona, vuit\u00e8 classificat amb 15 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[243,24,27,21],"class_list":["post-1461","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-infantils","tag-badalona","tag-fundacio-esportiva-grama","tag-nou-municipal","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=1461"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1461\/revisions"}],"predecessor-version":[{"id":1463,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1461\/revisions\/1463"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=1461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=1461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=1461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}