{"id":14556,"date":"2016-01-22T22:58:23","date_gmt":"2016-01-22T21:58:23","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=14556"},"modified":"2016-01-26T12:01:39","modified_gmt":"2016-01-26T11:01:39","slug":"comunicat-oficial-sancio-per-comportament-antiesportiu","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/comunicat-oficial-sancio-per-comportament-antiesportiu\/","title":{"rendered":"Comunicat Oficial: sanci\u00f3 per comportament antiesportiu"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/imagen-comunciado-oficial.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14557\" alt=\"imagen comunciado oficial\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/imagen-comunciado-oficial.jpg\" width=\"718\" height=\"302\" srcset=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/imagen-comunciado-oficial.jpg 718w, https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2016\/01\/imagen-comunciado-oficial-300x126.jpg 300w\" sizes=\"auto, (max-width: 718px) 100vw, 718px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">COMUNICAT OFICIAL:<\/p>\n<p style=\"text-align: justify;\">La Junta Directiva de la Fundaci\u00f3 Esportiva Grama, reunida a les 19:30h en comissi\u00f3 extraordin\u00e0ria a dia 20 de gener de 2016, emet aquest comunicat per fer p\u00fabliques les decisions que s\u2019han pres en vers a l\u2019actuaci\u00f3 del pare d\u2019un dels nostres jugadors contra la col\u00b7legiada del partit que enfrontava al nostre Juvenil C i la Penya Barcelonista Barcino el passat dissabte 16 de gener.<\/p>\n<p style=\"text-align: justify;\">En primer lloc volem mostrar la nostra <b><span style=\"text-decoration: underline;\">repulsa a qualsevol comportament antiesportiu<\/span><\/b> que es produeixi a dins de les instal\u00b7lacions que gestionem perqu\u00e8, com b\u00e9 sabeu, el nostre treball diari no es nom\u00e9s futbol\u00edstic si no que ens esforcem en cada entrenament, en cada partit i en cada moment de la nostra conviv\u00e8ncia dins de la Fundaci\u00f3 per <b><span style=\"text-decoration: underline;\">transmetre uns valors<\/span><\/b> que queden molt lluny del comportament que aquest pare va mostrar en la \u00faltima jornada de lliga.<\/p>\n<p style=\"text-align: justify;\">Per tant, despr\u00e9s de llegir l\u2019acta del partit, d\u2019estudiar el cas amb deteniment, recollir tota la informaci\u00f3 possible per part de testimonis i despr\u00e9s de rebre l\u2019advert\u00e8ncia de la Federaci\u00f3 Catalana de Futbol, fem p\u00fablic aquest comunicat amb els seg\u00fcents acords i consideracions:<\/p>\n<p style=\"text-align: justify;\">1)\u00a0\u00a0\u00a0\u00a0\u00a0 La Fundaci\u00f3 Esportiva Grama no permetr\u00e0 en cap moment un comportament antiesportiu a dins de les seves instal\u00b7lacions i com a mostra diem que va ser el propi personal de l\u2019Entitat el que va protegir a la col\u00b7legiada per tal d\u2019evitar possibles agressions a la sortida de l\u2019Estadi.<\/p>\n<p style=\"text-align: justify;\">2)\u00a0\u00a0\u00a0\u00a0\u00a0 Amb tota la informaci\u00f3 que hem pogut recopilar sobre els fets succe\u00efts estem d\u2019acord amb el que la col\u00b7legiada reflexa a\u00a0 l\u2019acta del partit per\u00f2 <b><span style=\"text-decoration: underline;\">no estem d\u2019acord<\/span><\/b> en el punt on es diu: <i>\u201cfaig constar que durant tot el partit he rebut insults masclistes i de menyspreu des d\u2019un sector de la grada que he pogut identificar com afici\u00f3 i pares de l\u2019equip local\u201d<\/i>.<\/p>\n<p style=\"text-align: justify;\">Mostrem el nostre desacord al respecte perqu\u00e8 sabem que les aficions estaven barrejades per les graderies del Nou Municipal i perqu\u00e8 el transcurs del partit va portar\u00a0 alternatives al marcador que descontentaven a uns i altres amb l\u2019actuaci\u00f3 arbitral. No considerem que es pugui acusar a l\u2019afici\u00f3 local de manera gen\u00e8rica, nom\u00e9s en el cas que estem tractant.<\/p>\n<p style=\"text-align: justify;\">3)\u00a0\u00a0\u00a0\u00a0\u00a0 Una vegada hem identificat a l\u2019infractor, pare i tutor d\u2019un dels nostres jugadors, mantenim oculta la seva identitat en tot el tractament p\u00fablic del cas per tal de respectar la llei de protecci\u00f3 de dades.<\/p>\n<p style=\"text-align: justify;\">4)\u00a0\u00a0\u00a0\u00a0\u00a0 Havent citat a l\u2019infractor a les nostres instal\u00b7lacions i havent reconegut personalment els fets que van succeir al partit abans mencionat, la Junta Directiva de la Fundaci\u00f3 Esportiva Grama li comunica la seva sanci\u00f3:<b><span style=\"text-decoration: underline;\"> de manera INDEFINIDA se li prohibeix l\u2019acc\u00e9s a les Instal\u00b7lacions del Nou Camp Municipal i del Municipal de les Oliveres pels fets succe\u00efts en el partit que mencionem en aquest comunicat. Tamb\u00e9 li recomanem que no acompanyi als seu fill quan el partit es disputi en camp contrari\u201d.<\/span><\/b><\/p>\n<p style=\"text-align: justify;\">El Jugador podr\u00e0 ser acompanyat per qualsevol familiar que no sigui l\u2019infractor.<b><span style=\"text-decoration: underline;\">\u00a0 <\/span><\/b><\/p>\n<p style=\"text-align: justify;\">5)\u00a0\u00a0\u00a0\u00a0\u00a0 A m\u00e9s, tamb\u00e9 li comuniquem la nostra intenci\u00f3 de\u00a0 cursar \u00a0denuncia legal als Mossos d\u2019Esquadra\u00a0 contra ell pels perjudicis que les seves accions puguin derivar-se contra la Fundaci\u00f3 Esportiva Grama. Encara aix\u00ed els Mossos han refusat la nostra denuncia explicant-nos que ha de ser la col\u00b7legiada qui denunci\u00ef els fets. En aquest cas la Fundaci\u00f3 actuar\u00e0 com a testimoni i aix\u00ed ho farem si ella decideix finalment interposar denuncia.<\/p>\n<p style=\"text-align: justify;\">6)\u00a0\u00a0\u00a0\u00a0\u00a0 Aquestes decisions i consideracions, a m\u00e9s de ser transmeses a la Federaci\u00f3 Catalana de Futbol, les farem p\u00fabliques mitjan\u00e7ant les nostres xarxes socials.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Acabem aquest comunicat insistint en el que hem dit en nombroses ocasions. Volem ser un exemple de valors i de comportament a dins i fora del camp. Aix\u00ed no \u00e9s la primera vegada que hem de prendre aquestes mesures sancionadores i no dubtarem en tornar a fer-ho si es dona el cas per\u00f2 confiem en tots els que conformem aquesta gran fam\u00edlia futbol\u00edstica ja que tenim el seny suficient per mostrar als m\u00e9s joves que el cam\u00ed a seguir \u00e9s el de l\u2019educaci\u00f3 i el respecte. Qualsevol altre cam\u00ed no te cabuda entre nosaltres.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Atentament,<\/p>\n<p style=\"text-align: justify;\">Junta Directiva de la Fundaci\u00f3 Esportiva Grama.<\/p>\n<p style=\"text-align: justify;\">\u00a0[divider]<\/p>\n<p style=\"text-align: justify;\">COMUNICADO OFICIAL:<\/p>\n<p style=\"text-align: justify;\">La Junta Directiva de la Fundaci\u00f3 Esportiva Grama, reunida a las 19: 30h en comisi\u00f3n extraordinaria a d\u00eda 20 de enero de 2016, emite este comunicado para hacer p\u00fablicas las decisiones que se han tomado en verso a la actuaci\u00f3n del padre de uno de nuestros jugadores contra la colegiada del partido que enfrentaba a nuestro Juvenil C y la Penya Barcelonista Barcino el pasado s\u00e1bado 16 de enero.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En primer lugar queremos mostrar nuestra <b><span style=\"text-decoration: underline;\">repulsa a cualquier comportamiento antideportivo<\/span><\/b> que se produzca dentro de las instalaciones que gestionamos porque, como bien sab\u00e9is, nuestro trabajo diario no es s\u00f3lo futbol\u00edstico sino que nos esforzamos en cada entrenamiento, en cada partido y en cada momento de nuestra convivencia dentro de la Fundaci\u00f3 para <b><span style=\"text-decoration: underline;\">transmitir unos valores<\/span><\/b> que quedan muy lejos del comportamiento que este padre mostr\u00f3 en la \u00faltima jornada de liga.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Por lo tanto, despu\u00e9s de leer el acta del partido, de estudiar el caso con detenimiento, recoger toda la informaci\u00f3n posible por parte de testigos y despu\u00e9s de recibir la advertencia de la Federaci\u00f3n Catalana de F\u00fatbol, \u200b\u200bhacemos p\u00fablico este comunicado con los siguientes acuerdos y consideraciones:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">1) La Fundaci\u00f3 Esportiva Grama no permitir\u00e1 en ning\u00fan momento un comportamiento antideportivo dentro de sus instalaciones y como muestra decimos que fue el propio personal de la Entidad el que protegi\u00f3 a la colegiada con el fin de evitar posibles agresiones a la salida del estadio.<\/p>\n<p style=\"text-align: justify;\">2) Con toda la informaci\u00f3n que hemos podido recopilar sobre los hechos sucedidos estamos de acuerdo con lo que la colegiada refleja en el acta del partido pero <b><span style=\"text-decoration: underline;\">no estamos de acuerdo<\/span><\/b> en el punto donde se dice: <i>\u00abhago constar que durante todo el partido he recibido insultos machistas y de desprecio desde un sector de la grada que he podido identificar como afici\u00f3n y padres del equipo local\u201d.<\/i><\/p>\n<p style=\"text-align: justify;\">Mostramos nuestro desacuerdo al respecto porque sabemos que las aficiones estaban mezcladas por las gradas del Nou Municipal y porque el transcurso del partido llev\u00f3 alternativas en el marcador que descontentaban a unos y otros con la actuaci\u00f3n arbitral. No consideramos que se pueda acusar a la afici\u00f3n local de manera gen\u00e9rica, s\u00f3lo en el caso que estamos tratando.<\/p>\n<p style=\"text-align: justify;\">3) Una vez hemos identificado al infractor, padre y tutor de uno de nuestros jugadores, mantenemos oculta su identidad en todo el tratamiento p\u00fablico del caso para respetar la ley de protecci\u00f3n de datos.<\/p>\n<p style=\"text-align: justify;\">4) Habiendo citado al infractor en nuestras instalaciones y habiendo reconocido personalmente los hechos que sucedieron en el partido antes mencionado, la Junta Directiva de la Fundaci\u00f3 Esportiva Grama le comunica su sanci\u00f3n: <b><span style=\"text-decoration: underline;\">de forma INDEFINIDA se le proh\u00edbe el acceso a las instalaciones del Nou Camp Municipal y del Municipal de les Oliveres por los hechos sucedidos en el partido que mencionamos en este comunicado. Tambi\u00e9n le recomendamos que no acompa\u00f1e a su hijo cuando el partido se dispute en campo contrario\u201d.<\/span><\/b><\/p>\n<p style=\"text-align: justify;\">El Jugador podr\u00e1 ser acompa\u00f1ado por cualquier familiar que no sea el infractor.<\/p>\n<p style=\"text-align: justify;\">5) Adem\u00e1s, tambi\u00e9n le comunicamos nuestra intenci\u00f3n de cursar denuncia legal a los Mossos contra \u00e9l por los perjuicios que de sus acciones puedan derivarse contra la Fundaci\u00f3 Esportiva Grama. A\u00fan as\u00ed, los Mossos han rechazado nuestra denuncia explic\u00e1ndonos que debe ser la colegiada quien denuncie los hechos. En este caso la Fundaci\u00f3 actuar\u00e1 como testigo y as\u00ed lo haremos si ella decide finalmente interponer denuncia.<\/p>\n<p style=\"text-align: justify;\">6) Estas decisiones y consideraciones, adem\u00e1s de ser transmitidas a la Federaci\u00f3n Catalana de F\u00fatbol, \u200b\u200blas haremos p\u00fablicas mediante nuestras redes sociales.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Acabamos este comunicado insistiendo en lo dicho en numerosas ocasiones. Queremos ser un ejemplo de valores y de comportamiento dentro y fuera del campo. As\u00ed no es la primera vez que tenemos que tomar estas medidas sancionadoras y no dudaremos en volver a hacerlo si se da el caso, pero confiamos en todos los que conformamos esta gran familia futbol\u00edstica ya que tenemos la cordura suficiente para mostrar a los m\u00e1s j\u00f3venes que el camino a seguir es el de la educaci\u00f3n y el respeto. Cualquier otro camino no tiene cabida entre nosotros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Atentamente,<\/p>\n<p style=\"text-align: justify;\">Junta Directiva de la Fundaci\u00f3n Deportiva Grama.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMUNICAT OFICIAL: La Junta Directiva de la Fundaci\u00f3 Esportiva Grama, reunida a les 19:30h en comissi\u00f3 extraordin\u00e0ria a dia 20 de gener de 2016, emet aquest comunicat per fer p\u00fabliques les decisions que s\u2019han pres en vers a l\u2019actuaci\u00f3 del pare d\u2019un dels nostres jugadors contra la col\u00b7legiada del partit que enfrontava al nostre Juvenil [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":14557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[23,1047,1048,1007,1023,1046],"class_list":["post-14556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-antonio-morales","tag-comportament-antiesportiu","tag-comunciado-oficial","tag-comunicat-oficial","tag-junta-directiva","tag-sancio-disciplinaria"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=14556"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14556\/revisions"}],"predecessor-version":[{"id":14559,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/14556\/revisions\/14559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media\/14557"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=14556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=14556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=14556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}