{"id":1222,"date":"2014-01-13T07:16:13","date_gmt":"2014-01-13T07:16:13","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=1222"},"modified":"2014-01-13T07:16:13","modified_gmt":"2014-01-13T07:16:13","slug":"el-cadet-b-segueix-invicte-davant-la-fundacio-hospitalet-per-4-2","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-cadet-b-segueix-invicte-davant-la-fundacio-hospitalet-per-4-2\/","title":{"rendered":"El Cadet B segueix invicte davant la Fundaci\u00f3 Hospitalet per 4-2"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-El\u00a0<strong>Cadet B de la Fundaci\u00f3 Esportiva Grama<\/strong>\u00a0segueix l\u00edder amb un cent per cent en vict\u00f2ries amb la aconseguida, la d\u00e9cima, davant la <strong>Fundaci\u00f3 Hospitalet<\/strong> per 4-2.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El segon i perseguidor, l&#8217;<strong>Escola Pia Sarri\u00e0<\/strong>, ens segueix a 11 punts.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Els joves jugadors dirigits per l\u2019<strong>\u00c1lex Abril <\/strong>van guanyar a la\u00a0<strong><strong>Fundaci\u00f3 Hospitalet<\/strong>, <\/strong>tercer per la cua amb nom\u00e9s 8 punts, per 4-2 encara que va ser un partit complicat per\u00f2 aix\u00f2 que primer van\u00a0aprofitar-se d&#8217;un autogol dels visitants al minut 14 i ja despr\u00e8s els gols de<strong> Marc Arreciado<\/strong> al minut 24, el de <strong>Alejandro P\u00e9rez<\/strong> nom\u00e8s quatre minuts despr\u00e8s al 28 van deixar el parcial arrollador de 3-0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Encara que es van acostar al 3-2, <strong>Daniel G\u00f3mez<\/strong> deix\u00e0 el definitiu 4-2 per a la <strong>Fundaci\u00f3 Grama<\/strong>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A la jornada 13 els tocaba viatjar a la Zona Franca, equip retirat de la competici\u00f3 junt amb la Fundaci\u00f3 Hermes i el Pubilla Casas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Al\u00e9 Grama!!!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">-El Cadete B de la Fundaci\u00f3n Deportiva Grama sigue l\u00edder con un cien por cien en victorias con la conseguida, la d\u00e9cima, ante la Fundaci\u00f3n Hospitalet por 4-2.<\/span><br \/>\n<span style=\"color: #000000;\">El segundo y perseguidor, la Escuela Pia Sarri\u00e0, nos sigue a 11 puntos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Los j\u00f3venes jugadores dirigidos por \u00c1lex Abril ganaron la Fundaci\u00f3n Hospitalet, tercero por la cola con s\u00f3lo 8 puntos, por 4-2 aunque fue un partido complicado pero esto que primero aprovecharse de un autogol de los visitantes en el minuto 14 y ya despu\u00e9s los goles de Marc Arreciado el minuto 24, el de Alejandro P\u00e9rez s\u00f3lo cuatro minutos despu\u00e9s al 28 dejaron el parcial arrollador de 3-0.<\/span><br \/>\n<span style=\"color: #000000;\">Aunque se acercaron al 3-2, Daniel G\u00f3mez dej\u00f3 el definitivo 4-2 para la Fundaci\u00f3n Grama.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la jornada 13 los tocaba viajar a la Zona Franca, equipo retirado de la competici\u00f3n junto con la Fundaci\u00f3n Hermes y el Pubilla Casas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al\u00e9 Grama!!!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-El\u00a0Cadet B de la Fundaci\u00f3 Esportiva Grama\u00a0segueix l\u00edder amb un cent per cent en vict\u00f2ries amb la aconseguida, la d\u00e9cima, davant la Fundaci\u00f3 Hospitalet per 4-2. El segon i perseguidor, l&#8217;Escola Pia Sarri\u00e0, ens segueix a 11 punts. Els joves jugadors dirigits per l\u2019\u00c1lex Abril van guanyar a la\u00a0Fundaci\u00f3 Hospitalet, tercer per la cua amb [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[178,20,194,27,21],"class_list":["post-1222","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-cadets","tag-escola-pia-sarria","tag-fundacio-grama","tag-fundacio-hospitalet","tag-nou-municipal","tag-santa-coloma"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":2,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1222\/revisions"}],"predecessor-version":[{"id":1408,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/1222\/revisions\/1408"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=1222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=1222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}