{"id":11316,"date":"2015-05-10T18:00:43","date_gmt":"2015-05-10T17:00:43","guid":{"rendered":"http:\/\/fegrama.cat\/web\/?p=11316"},"modified":"2015-05-10T18:00:43","modified_gmt":"2015-05-10T17:00:43","slug":"el-juvenil-a-va-golejar-al-camp-de-la-hermes","status":"publish","type":"post","link":"https:\/\/fegrama.cat\/web\/el-juvenil-a-va-golejar-al-camp-de-la-hermes\/","title":{"rendered":"El Juvenil \u00abA\u00bb va golejar al camp de la Hermes"},"content":{"rendered":"<p>Segona vict\u00f2ria consecutiva del Juvenil \u00abA\u00bb que conservar\u00e0 una jornada m\u00e9s el cinqu\u00e8 lloc de la classificaci\u00f3. Aquesta vegada els colomencs van guanyar 1-4 a la Fundaci\u00f3n Privada Hermes, equip que estava sol dos punts per darrere.<\/p>\n<p>Molt bon partit de l&#8217;equip de Toni Rovira, dominant de principi a fi i gaudint de nombroses ocasions per poder fins i tot augmentar molt m\u00e9s el nombre de gols marcats. El primer gol al Municipal Can Buxeres de L&#8217;Hospitalet de Llobregat no trigaria a arribar, al minut 8 de partit Brayan Caicedo avan\u00e7ava a l&#8217;equip despr\u00e9s d&#8217;una gran jugada col\u00b7lectiva.<\/p>\n<p>Quinze minuts despr\u00e9s de nou Brayan marcava i posava el 0-2 al marcador. Dominava la Grama per\u00f2 de sobte en l&#8217;\u00fanica arribada en tota la primera part de la Hermes arribaria un gol, l&#8217;ex-jugador de la F.E.Grama Godbless retallava dist\u00e0ncies en el marcador per anar-nos al descans amb 1-2.<\/p>\n<p>A la segona meitat el partit va estar m\u00e9s anivellat per\u00f2 despr\u00e9s del gol de Gorka Mart\u00ednez al minut 60 de partit va fer que de nou els colomencs tornessin a tenir el control del partit; en el minut 70 Iv\u00e1n marcava el definitiu 1-4. Diumenge que ve al Nou Municipal s&#8217;acomiadaran la temporada.<\/p>\n<p><a href=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/12\/JUVENIL-A-2FUNDACIO-GRAMA-SANTA-COLOMA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8383\" alt=\"JUVENIL A (2)FUNDACIO GRAMA SANTA COLOMA\" src=\"https:\/\/fegrama.cat\/web\/wp-content\/uploads\/2014\/12\/JUVENIL-A-2FUNDACIO-GRAMA-SANTA-COLOMA.jpg\" width=\"640\" height=\"480\" \/><\/a><\/p>\n<p>Segunda victoria consecutiva del Juvenil \u00abA\u00bb que conservar\u00e1 una jornada m\u00e1s el quinto puesto de la clasificaci\u00f3n. Esta vez los colomenses ganaron 1-4 a la Fundaci\u00f3n Privada Hermes, equipo que estaba solo dos puntos por detr\u00e1s.<\/p>\n<p>Muy buen partido del equipo de Toni Rovira, dominado de principio a fin y gozando de numerosas ocasiones para poder incluso aumentar mucho m\u00e1s el n\u00famero de goles marcados. El primer gol en el Municipal Can Buxeres de L&#8217;Hospitalet de Llobregat no tardar\u00eda en llegar, en el minuto 8 de partido Brayan Caicedo adelantaba al equipo tras una gran jugada colectiva.<\/p>\n<p>Quince minutos despu\u00e9s de nuevo Brayan marcaba y pon\u00eda el 0-2 en el marcador. Dominaba la Grama pero de repente en la \u00fanica llegada en toda la primera parte de la Hermes llegar\u00eda un gol, el ex-jugador de la F.E.Grama Godbless recortaba distancias en el marcador para irnos al descanso con 1-2.<\/p>\n<p>En la segunda mitad el partido estuvo m\u00e1s nivelado pero tras el gol de Gorka Mart\u00ednez en el minuto 60 de partido hizo que de nuevo los colomenses volvieran a tener el control del partido; en el minuto 70 Iv\u00e1n marcaba el definitivo 1-4. El pr\u00f3ximo domingo en el Nou Municipal despedir\u00e1n la temporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segona vict\u00f2ria consecutiva del Juvenil \u00abA\u00bb que conservar\u00e0 una jornada m\u00e9s el cinqu\u00e8 lloc de la classificaci\u00f3. Aquesta vegada els colomencs van guanyar 1-4 a la Fundaci\u00f3n Privada Hermes, equip que estava sol dos punts per darrere. Molt bon partit de l&#8217;equip de Toni Rovira, dominant de principi a fi i gaudint de nombroses ocasions [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[399,24,393],"class_list":["post-11316","post","type-post","status-publish","format-standard","hentry","category-base-inclusiu","category-juvenils","tag-fegrama","tag-fundacio-esportiva-grama","tag-fundacion-privada-hermes"],"_links":{"self":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/11316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/comments?post=11316"}],"version-history":[{"count":1,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/11316\/revisions"}],"predecessor-version":[{"id":11317,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/posts\/11316\/revisions\/11317"}],"wp:attachment":[{"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/media?parent=11316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/categories?post=11316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fegrama.cat\/web\/wp-json\/wp\/v2\/tags?post=11316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}